{"id":1698,"date":"2021-05-12T21:39:45","date_gmt":"2021-05-13T00:39:45","guid":{"rendered":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/"},"modified":"2022-11-11T14:16:53","modified_gmt":"2022-11-11T17:16:53","slug":"entendendo-o-icms-importacao","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/entendendo-o-icms-importacao\/","title":{"rendered":"ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O"},"content":{"rendered":"<p>Imposto sobre opera\u00e7\u00f5es relativas \u00e0 circula\u00e7\u00e3o de mercadorias e sobre presta\u00e7\u00e3o de servi\u00e7os de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o (ICMS)<\/p>\n<p>Diferente dos demais tributos incidentes na importa\u00e7\u00e3o, que s\u00e3o de compet\u00eancia da Uni\u00e3o, o ICMS \u00e9 institu\u00eddo pelos Estados e Distrito Federal, conforme artigo 155, II, da Constitui\u00e7\u00e3o Federal.<\/p>\n<p>Da mesma forma, est\u00e1 disposi\u00e7\u00e3o consta no artigo 1\u00b0 da Lei Complementar n\u00b0 87\/1996, conhecida tamb\u00e9m como Lei Kandir em homenagem ao seu autor, o ex-deputado federal Ant\u00f4nio Kandir.<\/p>\n<p>A Constitui\u00e7\u00e3o Federal de 1988 deu compet\u00eancia aos Estados-membros da Federa\u00e7\u00e3o a regular o ICMS, criando o \u201cFederalismo Cooperativo\u201d, visando uma coopera\u00e7\u00e3o entre os Estados de forma harm\u00f4nica. Por\u00e9m na pr\u00e1tica o que aconteceu foi a chamada \u201cguerra fiscal\u201d, onde cada Estado com objetivo de atrair investimentos come\u00e7ou a criar e praticar benef\u00edcios sem regras fundamentadas.<\/p>\n<p>Cabe destacar que os Estados n\u00e3o podem conceder benef\u00edcios sem uma regra fundamentada, devendo passar pela aprova\u00e7\u00e3o do Conselho Nacional de Pol\u00edtica Fazend\u00e1ria (CONFAZ) que \u00e9 constitu\u00eddo pelos Secret\u00e1rios da Fazenda dos Estados e do Distrito Federal e presidido pelo Ministro da Fazenda ou seu representante. O objetivo do \u00f3rg\u00e3o \u00e9 realizar a\u00e7\u00f5es para elabora\u00e7\u00e3o de pol\u00edticas para harmoniza\u00e7\u00e3o dos procedimentos e normas referentes ao ICMS.<\/p>\n<p>O fato gerador do ICMS\/importa\u00e7\u00e3o \u00e9 a entrada de bem (mercadoria) importado, tendo a sua incid\u00eancia no momento do desembara\u00e7o aduaneiro (ato da fiscaliza\u00e7\u00e3o aduaneira em liberar a entrada da mercadoria importada). Tendo como sujeito ativo (quem exige o tributo) os Estados e Distrito Federal, e como sujeito passivo (respons\u00e1vel pelo pagamento) o importador.<\/p>\n<p>A base de c\u00e1lculo do ICMS\/importa\u00e7\u00e3o deve respeitar a regra de tratamento nacional, devendo os bens importados ter a mesma carga tribut\u00e1ria dos bens internos. De acordo com a Constitui\u00e7\u00e3o Federal e da Lei Kandir, a base de c\u00e1lculo deve ser composta dos seguintes fatores:<\/p>\n<p>&#8211; Valor da mercadoria;<\/p>\n<p>&#8211; Imposto de importa\u00e7\u00e3o;<\/p>\n<p>&#8211; IPI\/importa\u00e7\u00e3o;<\/p>\n<p>&#8211; Imposto sobre opera\u00e7\u00f5es de c\u00e2mbio;<\/p>\n<p>&#8211; Outros impostos;<\/p>\n<p>&#8211; Contribui\u00e7\u00f5es; e<\/p>\n<p>&#8211; Despesas aduaneiras.<\/p>\n<p>As al\u00edquotas s\u00e3o institu\u00eddas por meio de Leis Estaduais e Distritais.<\/p>\n<p>Cabe refor\u00e7ar que a entrega da mercadoria est\u00e1 condicionada ao pagamento do ICMS ou exonera\u00e7\u00e3o atrav\u00e9s de GLME (guia para libera\u00e7\u00e3o de mercadoria estrangeira sem comprova\u00e7\u00e3o do recolhimento de ICMS), conforme o art. 54 da Instru\u00e7\u00e3o Normativa n\u00b0 680\/2006 que disciplina o despacho aduaneiro de importa\u00e7\u00e3o.<\/p>\n<p><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm\" target=\"_blank\" rel=\"nofollow noopener\">Constitui\u00e7\u00e3o Federal<\/a><\/p>\n<p><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/Leis\/lcp\/Lcp87.htm\" target=\"_blank\" rel=\"nofollow noopener\" data-artdeco-is-focused=\"true\">Lei Complementar n\u00b0 87\/1996 (Lei Kandir)<\/a><\/p>\n<p><a href=\"http:\/\/normas.receita.fazenda.gov.br\/sijut2consulta\/link.action?visao=anotado&#038;idAto=15618\" target=\"_blank\" rel=\"nofollow noopener\">Instru\u00e7\u00e3o Normativa n\u00b0 680\/2006<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Em caso de d\u00favidas conte conosco!!<br \/>\n<a href=\"https:\/\/mastersul.com.br\/contato\/\">Contato Mastersul<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Mais conte\u00fado sobre ICMS voc\u00ea encontra <a href=\"https:\/\/mastersul.com.br\/blog\/novo-regulamento-do-icms-do-parana\/\">aqui<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<div id=\"ember1692\" class=\"feed-shared-avatar-image b0 reader-related-content__author-image member ember-view\"><\/div>\n<div class=\"display-flex\">\n<h6 class=\"Sans-17px-black-85%-semibold reader-author-summary__meta-author-detail--has-hover\" style=\"text-align: center;\">BRUNO GOUDEL<\/h6>\n<\/div>\n<h6 class=\"Sans-15px-black-55%\" style=\"text-align: center;\">Consultor Aduaneiro na MASTERSUL COMEX<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Imposto sobre opera\u00e7\u00f5es relativas \u00e0 circula\u00e7\u00e3o de mercadorias e sobre presta\u00e7\u00e3o de servi\u00e7os de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o (ICMS) Diferente dos demais tributos incidentes na importa\u00e7\u00e3o, que s\u00e3o de compet\u00eancia da Uni\u00e3o, o ICMS \u00e9 institu\u00eddo pelos Estados e Distrito Federal, conforme artigo 155, II, da Constitui\u00e7\u00e3o Federal. Da mesma forma, est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1699,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/entendendo-o-icms-importacao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O\" \/>\n<meta property=\"og:description\" content=\"Imposto sobre opera\u00e7\u00f5es relativas \u00e0 circula\u00e7\u00e3o de mercadorias e sobre presta\u00e7\u00e3o de servi\u00e7os de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o (ICMS) Diferente dos demais tributos incidentes na importa\u00e7\u00e3o, que s\u00e3o de compet\u00eancia da Uni\u00e3o, o ICMS \u00e9 institu\u00eddo pelos Estados e Distrito Federal, conforme artigo 155, II, da Constitui\u00e7\u00e3o Federal. Da mesma forma, est\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/entendendo-o-icms-importacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-13T00:39:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-11T17:16:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/master_2018_0075.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Amarante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Amarante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/\"},\"author\":{\"name\":\"Gabriel Amarante\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"headline\":\"ENTENDENDO O ICMS\\\/IMPORTA\u00c7\u00c3O\",\"datePublished\":\"2021-05-13T00:39:45+00:00\",\"dateModified\":\"2022-11-11T17:16:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/\"},\"wordCount\":482,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/master_2018_0075.png\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/\",\"name\":\"ENTENDENDO O ICMS\\\/IMPORTA\u00c7\u00c3O\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/master_2018_0075.png\",\"datePublished\":\"2021-05-13T00:39:45+00:00\",\"dateModified\":\"2022-11-11T17:16:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/master_2018_0075.png\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/master_2018_0075.png\",\"width\":850,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/entendendo-o-icms-importacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENTENDENDO O ICMS\\\/IMPORTA\u00c7\u00c3O\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\",\"name\":\"Gabriel Amarante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"caption\":\"Gabriel Amarante\"},\"sameAs\":[\"https:\\\/\\\/gabrielfreelancer.com.br\"],\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/amarante\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/entendendo-o-icms-importacao\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O[:] - Mastersul","og_description":"Imposto sobre opera\u00e7\u00f5es relativas \u00e0 circula\u00e7\u00e3o de mercadorias e sobre presta\u00e7\u00e3o de servi\u00e7os de transporte interestadual e intermunicipal e de comunica\u00e7\u00e3o (ICMS) Diferente dos demais tributos incidentes na importa\u00e7\u00e3o, que s\u00e3o de compet\u00eancia da Uni\u00e3o, o ICMS \u00e9 institu\u00eddo pelos Estados e Distrito Federal, conforme artigo 155, II, da Constitui\u00e7\u00e3o Federal. Da mesma forma, est\u00e1 [&hellip;]","og_url":"https:\/\/mastersul.com.br\/en\/entendendo-o-icms-importacao\/","og_site_name":"Mastersul","article_published_time":"2021-05-13T00:39:45+00:00","article_modified_time":"2022-11-11T17:16:53+00:00","og_image":[{"width":850,"height":350,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/master_2018_0075.png","type":"image\/png"}],"author":"Gabriel Amarante","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gabriel Amarante","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/"},"author":{"name":"Gabriel Amarante","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"headline":"ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O","datePublished":"2021-05-13T00:39:45+00:00","dateModified":"2022-11-11T17:16:53+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/"},"wordCount":482,"commentCount":0,"image":{"@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/master_2018_0075.png","articleSection":["Sem categoria"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/","url":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/","name":"ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/master_2018_0075.png","datePublished":"2021-05-13T00:39:45+00:00","dateModified":"2022-11-11T17:16:53+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"breadcrumb":{"@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/master_2018_0075.png","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/master_2018_0075.png","width":850,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/entendendo-o-icms-importacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"ENTENDENDO O ICMS\/IMPORTA\u00c7\u00c3O"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83","name":"Gabriel Amarante","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","caption":"Gabriel Amarante"},"sameAs":["https:\/\/gabrielfreelancer.com.br"],"url":"https:\/\/mastersul.com.br\/en\/author\/amarante\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/1698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=1698"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/1698\/revisions"}],"predecessor-version":[{"id":2440,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/1698\/revisions\/2440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/1699"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=1698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=1698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=1698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}