{"id":1867,"date":"2021-03-30T21:45:06","date_gmt":"2021-03-31T00:45:06","guid":{"rendered":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/"},"modified":"2022-11-10T15:20:15","modified_gmt":"2022-11-10T18:20:15","slug":"por-que-contratar-um-seguro-internacional-de-cargas","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/por-que-contratar-um-seguro-internacional-de-cargas\/","title":{"rendered":"Por que contratar um seguro internacional de cargas?"},"content":{"rendered":"<p>Imagine a seguinte situa\u00e7\u00e3o: sua carga est\u00e1 em tr\u00e2nsito no Oceano Atl\u00e2ntico quando um acidente acontece e ela cai no mar. E a\u00ed? Quem deve arcar com os preju\u00edzos? Por mais que toda opera\u00e7\u00e3o log\u00edstica seja desenhada de forma inteligente, imprevistos podem acontecer. Por isso, depois de escolher o melhor modal para a sua importa\u00e7\u00e3o e exporta\u00e7\u00e3o, \u00e9 preciso estar ciente de que, independe de qual o transporte &#8211; terrestre, mar\u00edtimo ou a\u00e9reo -, todos apresentam riscos e a melhor maneira de se prevenir quanto a isso \u00e9 contratando um Seguro Internacional de Cargas.<\/p>\n<p>&nbsp;<\/p>\n<h4>CONTRATA\u00c7\u00c3O DE SEGURO INTERNACIONAL DE CARGAS NO EXTERIOR<\/h4>\n<p>O seguro internacional de cargas \u00e9 facultativo, no entanto, se for contratado, tem que ser com companhia de seguros estabelecida no Brasil, conforme estabelece a legisla\u00e7\u00e3o securit\u00e1ria.<\/p>\n<p>Para a contrata\u00e7\u00e3o de seguro de transporte internacional de importa\u00e7\u00e3o no exterior, o importador deve obedecer \u00e0s normas estabelecidas na <a href=\"http:\/\/www2.susep.gov.br\/bibliotecaweb\/docOriginal.aspx?tipo=1&#038;codigo=25945\">Circular 392\/2009<\/a> da Superintend\u00eancia de Seguros Privados (Susep), dentre as quais a que ordena que o importador tenha que consultar e receber a negativa de no m\u00ednimo dez seguradoras brasileiras que operem com seguros de transportes.<\/p>\n<p>Cuidado para n\u00e3o confundir importar CIF ou CIP com contratar seguro no exterior, s\u00e3o dois procedimentos distintos! Na importa\u00e7\u00e3o CIF\/CIP, o importador realiza uma compra, cuja mercadoria lhe foi vendida com a garantia de seguro de transporte pela ap\u00f3lice do exportador. Neste tipo de importa\u00e7\u00e3o, o comprador brasileiro n\u00e3o tem contato com a seguradora do exportador, \u00e9 apenas o benefici\u00e1rio do seguro. J\u00e1 o seguro contratado no exterior requer a celebra\u00e7\u00e3o de um contrato de seguro com uma seguradora estrangeira e remessa de valores para pagamento do pr\u00eamio negociado.<\/p>\n<p>&nbsp;<\/p>\n<h4>O QUE ESTABELECE AS NORMAS DA CIRCULAR?<\/h4>\n<p>Para contrata\u00e7\u00f5es relativas \u00e0 riscos e que n\u00e3o tenham obtido cobertura no Pa\u00eds, a SUSEP poder\u00e1, a qualquer tempo, exigir que o segurado e\/ou o corretor apresentem os seguintes documentos:<\/p>\n<p>I &#8211; C\u00f3pia de consultas efetuadas a, no m\u00ednimo, 10 (dez) sociedades seguradoras brasileiras que operem no ramo de seguro em que se enquadre o risco, devendo ser as consultas iguais, para todas as seguradoras;<\/p>\n<p>II &#8211; C\u00f3pia dos documentos emitidos pelas seguradoras mencionadas no inciso anterior, com a respectiva negativa para a cobertura do seguro, com a justificativa apresentada para o posicionamento;<\/p>\n<p>III &#8211; C\u00f3pia da consulta efetuada \u00e0 seguradora no exterior, com tradu\u00e7\u00e3o juramentada no idioma nacional, nos mesmos termos daquelas efetuadas \u00e0s seguradoras nacionais.<\/p>\n<p>A contrata\u00e7\u00e3o de seguro no exterior para cobertura de riscos no exterior facultada \u00e0s pessoas jur\u00eddicas dever\u00e1 ser informada \u00e0 SUSEP em at\u00e9 60 (sessenta) dias contados do in\u00edcio de vig\u00eancia do risco, nos termos da correspond\u00eancia cujo modelo consta do Anexo III \u00e0 presente Circular.<\/p>\n<p>&nbsp;<\/p>\n<h4>TIPOS DE SEGURO INTERNACIONAL<\/h4>\n<p>A contrata\u00e7\u00e3o do Seguro Internacional de Carga segue as pr\u00e1ticas dos <a href=\"https:\/\/mastersul.com.br\/blog\/incoterms-comercio-internacional\/\">Incoterms<\/a>, que garantem os direitos e normatizam as obriga\u00e7\u00f5es e responsabilidades tanto dos importadores quanto dos exportadores. \u00c9 importante levar isso em considera\u00e7\u00e3o na hora de contratar o seu seguro, bem como o tipo de modal escolhido para o transporte da mercadoria.<\/p>\n<p>Os seguros podem ser contratados pelo dono da mercadoria (comprador\/importador) ou por quem est\u00e1 vendendo (exportador). Por esta raz\u00e3o, conhecer o Incoterm escolhido para cada opera\u00e7\u00e3o e levar em considera\u00e7\u00e3o os riscos que a viagem oferece \u00e9 fundamental para definir qual o tipo de seguro contratar. Vale ressaltar que todos esses pontos devem ser acordados durante a negocia\u00e7\u00e3o entre as parte envolvidas.<\/p>\n<p>Atualmente, existem dois tipos de seguro:<\/p>\n<p><strong>1. Cobertura B\u00e1sica Ampla A:<\/strong> garante a cobertura de preju\u00edzos decorrentes de acidentes com o ve\u00edculo e tamb\u00e9m das causas externas, como roubos, avarias e extravios;<\/p>\n<p><strong>2. Cobertura B\u00e1sica Restrita B e C:<\/strong> garante a cobertura de preju\u00edzos decorrentes de danos ou perdas provenientes de acidentes com o ve\u00edculo transportado.<\/p>\n<p>&nbsp;<\/p>\n<h4>QUAL A IMPORT\u00c2NCIA DO SEGURO INTERNACIONAL DE CARGAS?<\/h4>\n<p>Mesmo contando com a assist\u00eancia de um agente de cargas de sua confian\u00e7a, existem uma s\u00e9rie de fatores externos que podem interferir no andamento de uma opera\u00e7\u00e3o internacional e \u00e9 essencial estar preparado para qualquer tipo de situa\u00e7\u00e3o.<\/p>\n<p>Apesar de n\u00e3o ser obrigat\u00f3rio, o Seguro Internacional \u00e9 fundamental para que o respons\u00e1vel pela carga, e at\u00e9 mesmo a transportadora que realiza o frete, n\u00e3o tenham nenhum tipo de preju\u00edzo em caso de imprevistos.<\/p>\n<p>O seguro, de forma geral, oferece cobertura de eventuais incidentes como perdas, avarias e extravios. O que garante tranquilidade nos processos de importa\u00e7\u00e3o e exporta\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h4>EVITE DOR DE CABE\u00c7A!<\/h4>\n<p>Proteja sua carga para evitar custos desnecess\u00e1rios na sua opera\u00e7\u00e3o. Fale com a gente e conhe\u00e7a as melhores solu\u00e7\u00f5es em seguro internacional, com ap\u00f3lices abertas, por viagem e por per\u00edodo. S\u00e3o opera\u00e7\u00f5es inteligentes, simples e r\u00e1pidas. Afinal, um bom neg\u00f3cio \u00e9 aquele que prev\u00ea o imprevisto!<br \/>\ncontato@mastersul.com.br | 41 3024 0100<\/p>\n<hr \/>\n<p>Veja nossos \u00faltimos posts e fique por dentro das atualiza\u00e7\u00f5es do Com\u00e9rcio Exterior:<\/p>\n<p>Como ficou o COMEX no novo Minist\u00e9rio da Economia sem o MDIC? &#8211; <a href=\"https:\/\/mastersul.com.br\/blog\/como-ficou-o-comex-no-novo-ministerio-da-economia-sem-o-mdic\/\">clique aqui<\/a><br \/>\nAcordo Mercosul e UE: o que isso impacta em seus processos internacionais &#8211;\u00a0<a href=\"https:\/\/mastersul.com.br\/blog\/acordo-mercosul-e-ue-o-que-isso-impacta-em-seus-processos-internacionais\/\">clique aqui<\/a><br \/>\nFeriados Internacionais para o segundo semestre de 2019 &#8211; <a href=\"https:\/\/mastersul.com.br\/blog\/feriados-internacionais-para-o-segundo-semestre-de-2019\/\">clique aqui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagine a seguinte situa\u00e7\u00e3o: sua carga est\u00e1 em tr\u00e2nsito no Oceano Atl\u00e2ntico quando um acidente acontece e ela cai no mar. E a\u00ed? Quem deve arcar com os preju\u00edzos? Por mais que toda opera\u00e7\u00e3o log\u00edstica seja desenhada de forma inteligente, imprevistos podem acontecer. Por isso, depois de escolher o melhor modal para a sua importa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1868,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por que contratar um seguro internacional de cargas?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/por-que-contratar-um-seguro-internacional-de-cargas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por que contratar um seguro internacional de cargas?\" \/>\n<meta property=\"og:description\" content=\"Imagine a seguinte situa\u00e7\u00e3o: sua carga est\u00e1 em tr\u00e2nsito no Oceano Atl\u00e2ntico quando um acidente acontece e ela cai no mar. E a\u00ed? Quem deve arcar com os preju\u00edzos? Por mais que toda opera\u00e7\u00e3o log\u00edstica seja desenhada de forma inteligente, imprevistos podem acontecer. Por isso, depois de escolher o melhor modal para a sua importa\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/por-que-contratar-um-seguro-internacional-de-cargas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-31T00:45:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T18:20:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_proteja_sua_carga_10_07_2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Amarante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Amarante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/\"},\"author\":{\"name\":\"Gabriel Amarante\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"headline\":\"Por que contratar um seguro internacional de cargas?\",\"datePublished\":\"2021-03-31T00:45:06+00:00\",\"dateModified\":\"2022-11-10T18:20:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/\"},\"wordCount\":913,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_proteja_sua_carga_10_07_2019.jpg\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/\",\"name\":\"Por que contratar um seguro internacional de cargas?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_proteja_sua_carga_10_07_2019.jpg\",\"datePublished\":\"2021-03-31T00:45:06+00:00\",\"dateModified\":\"2022-11-10T18:20:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_proteja_sua_carga_10_07_2019.jpg\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_proteja_sua_carga_10_07_2019.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/por-que-contratar-um-seguro-internacional-de-cargas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por que contratar um seguro internacional de cargas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\",\"name\":\"Gabriel Amarante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"caption\":\"Gabriel Amarante\"},\"sameAs\":[\"https:\\\/\\\/gabrielfreelancer.com.br\"],\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/amarante\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por que contratar um seguro internacional de cargas?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/por-que-contratar-um-seguro-internacional-de-cargas\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]Por que contratar um seguro internacional de cargas?[:] - Mastersul","og_description":"Imagine a seguinte situa\u00e7\u00e3o: sua carga est\u00e1 em tr\u00e2nsito no Oceano Atl\u00e2ntico quando um acidente acontece e ela cai no mar. E a\u00ed? Quem deve arcar com os preju\u00edzos? Por mais que toda opera\u00e7\u00e3o log\u00edstica seja desenhada de forma inteligente, imprevistos podem acontecer. Por isso, depois de escolher o melhor modal para a sua importa\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/mastersul.com.br\/en\/por-que-contratar-um-seguro-internacional-de-cargas\/","og_site_name":"Mastersul","article_published_time":"2021-03-31T00:45:06+00:00","article_modified_time":"2022-11-10T18:20:15+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_proteja_sua_carga_10_07_2019.jpg","type":"image\/jpeg"}],"author":"Gabriel Amarante","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gabriel Amarante","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/"},"author":{"name":"Gabriel Amarante","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"headline":"Por que contratar um seguro internacional de cargas?","datePublished":"2021-03-31T00:45:06+00:00","dateModified":"2022-11-10T18:20:15+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/"},"wordCount":913,"commentCount":0,"image":{"@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_proteja_sua_carga_10_07_2019.jpg","articleSection":["Sem categoria"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/","url":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/","name":"Por que contratar um seguro internacional de cargas?","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_proteja_sua_carga_10_07_2019.jpg","datePublished":"2021-03-31T00:45:06+00:00","dateModified":"2022-11-10T18:20:15+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"breadcrumb":{"@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_proteja_sua_carga_10_07_2019.jpg","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_proteja_sua_carga_10_07_2019.jpg","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/por-que-contratar-um-seguro-internacional-de-cargas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Por que contratar um seguro internacional de cargas?"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83","name":"Gabriel Amarante","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","caption":"Gabriel Amarante"},"sameAs":["https:\/\/gabrielfreelancer.com.br"],"url":"https:\/\/mastersul.com.br\/en\/author\/amarante\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/1867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=1867"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/1867\/revisions"}],"predecessor-version":[{"id":2326,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/1867\/revisions\/2326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/1868"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=1867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=1867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=1867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}