{"id":2126,"date":"2021-11-05T21:53:30","date_gmt":"2021-11-06T00:53:30","guid":{"rendered":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/"},"modified":"2022-11-09T10:47:30","modified_gmt":"2022-11-09T13:47:30","slug":"saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/","title":{"rendered":"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">No dia 26 de mar\u00e7o de 1991, o <strong>Tratado de Assun\u00e7\u00e3o<\/strong>, que deu origem ao Mercado Comum do Sul, foi assinado pelos pa\u00edses: Argentina, Brasil, Paraguai e Uruguai. De l\u00e1 para c\u00e1, muita coisa aconteceu: <strong>acordos comerciais foram assinados, encontros diplom\u00e1ticos foram realizados,<\/strong> al\u00e9m de outros pa\u00edses come\u00e7arem a prestar aten\u00e7\u00e3o no bloco econ\u00f4mico formado pelas na\u00e7\u00f5es sul-americanas.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Em meio a tanta hist\u00f3ria, uma coisa \u00e9 certa: <strong>o Mercosul \u00e9 muito importante para o com\u00e9rcio internacional do Brasil,<\/strong> al\u00e9m de ser um facilitador nas rela\u00e7\u00f5es comerciais com outros pa\u00edses do mundo. Por isso, para celebrar os <strong>30 anos do Mercosul,<\/strong> escrevemos um artigo especial com todas as informa\u00e7\u00f5es que voc\u00ea precisa saber. Boa leitura!<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Um pouquinho de hist\u00f3ria<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Criar um bloco econ\u00f4mico que aproximasse os pa\u00edses da Am\u00e9rica Latina sempre foi um objetivo. Ainda na d\u00e9cada de 40, foi criada a Comiss\u00e3o Econ\u00f4mica para a Am\u00e9rica Latina (CEPAL), e na d\u00e9cada de 60 vimos a Associa\u00e7\u00e3o Latino-Americana de Livre Com\u00e9rcio (ALALC) propor uma ideia de Mercado Comum entre os pa\u00edses. Mas <strong>foi apenas nos anos 90 que a ideia foi para a frente com a cria\u00e7\u00e3o do Mercosul.<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Ap\u00f3s a cria\u00e7\u00e3o do bloco econ\u00f4mico, pa\u00edses como Chile, Peru, Col\u00f4mbia, Equador, Guiana e Suriname tornaram-se Estados Associados, ou seja, sem participa\u00e7\u00e3o decis\u00f3ria nas reuni\u00f5es do bloco. Em 2012, a Venezuela tornou-se um Estado Parte, com poder de decis\u00e3o, mas devido a crise pol\u00edtica e econ\u00f4mica do pa\u00eds ele foi suspenso do bloco em 2016.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Mercosul e o Brasil<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">O bloco econ\u00f4mico formado pelos pa\u00edses da Am\u00e9rica do Sul representa <strong>uma oportunidade de entrada no mercado internacional<\/strong> para as empresas brasileiras. Isso porque as na\u00e7\u00f5es membro do Mercosul possuem culturas semelhantes e log\u00edstica facilitada, ou seja, o transporte de mercadorias pode ser realizado atrav\u00e9s dos modais mar\u00edtimo ou rodovi\u00e1rio.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Para quem est\u00e1 come\u00e7ando a importar\/exportar, <strong>apostar nos pa\u00edses membros do Mercosul \u00e9 uma \u00f3tima op\u00e7\u00e3o<\/strong> devido a rela\u00e7\u00e3o pr\u00f3xima das na\u00e7\u00f5es e valores competitivos nas opera\u00e7\u00f5es internacionais.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">O Mercosul fortalece a economia regional, aumenta o interc\u00e2mbio de tecnologias entre os pa\u00edses e favorece as exporta\u00e7\u00f5es e importa\u00e7\u00f5es para as empresas. Separamos aqui\u00a0<strong>tr\u00eas vantagens<\/strong>\u00a0do Mercosul para o Brasil:<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>01 &#8211; Isen\u00e7\u00e3o do Imposto de Importa\u00e7\u00e3o:<\/strong>\u00a0alguns produtos que circulam entre os pa\u00edses membros do Bloco Econ\u00f4mico s\u00e3o beneficiados com a isen\u00e7\u00e3o do imposto de importa\u00e7\u00e3o. Isso torna a opera\u00e7\u00e3o como um todo muito mais competitiva.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Para se usufruir desta vantagem, o produto deve ter um \u201c\u00edndice de nacionaliza\u00e7\u00e3o\u201d de 60%, ou seja, 60% do produto deve ter sido produzido em um dos pa\u00edses membros. Isso pode ser comprovado a partir do Certificado de Origem.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>02 &#8211; Tarifa Externa Comum (TEC):<\/strong>\u00a0trata-se da tarifa aduaneira estabelecida pelos pa\u00edses do Mercosul para importa\u00e7\u00e3o de produtos de pa\u00edses externos. Isso serve como uma estrat\u00e9gia para aumentar a competitividade dos mercados do bloco. Ela pode variar de 0% a 20%.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>03 &#8211; Acordos Internacionais:<\/strong>\u00a0uma das maiores vantagens em ser membro do Mercosul s\u00e3o os acordos firmados internacionalmente com outros pa\u00edses. A partir deles, a burocracia nos processos internacionais \u00e9 reduzida e novas oportunidades de neg\u00f3cio surgem. Separamos uma lista atualizada com todos os Acordos em vig\u00eancia no pr\u00f3ximo t\u00f3pico.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Mercosul e as Rela\u00e7\u00f5es Internacionais<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Atualmente, existem quatro Acordos Internacionais em vig\u00eancias. S\u00e3o eles:<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>01 &#8211; Tratado de Livre Com\u00e9rcio (TLC) com Israel:<\/strong>\u00a0firmado em 2007, durante e XXXIV Reuni\u00e3o da C\u00fapula do Mercado Comum do Sul e Estados associados, este foi o primeiro TLC do bloco com um pa\u00eds fora da Am\u00e9rica do Sul. O tratado cobre 90% do fluxo comercial entre os pa\u00edses e os principais produtos exportados do Mercosul s\u00e3o commodities, gr\u00e3os, cal\u00e7ados, autom\u00f3veis, maquinaria pesada e avi\u00f5es. J\u00e1 Israel exporta software, agroqu\u00edmicos e produtos de alta tecnologia;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>02 &#8211; Tratado de Livre Com\u00e9rcio com o Egito:<\/strong>\u00a0assinado em 2010, o acordo abriu um mercado de 76 milh\u00f5es de consumidores para produtos prim\u00e1rios e industrializados do bloco sul-americano. Com o TLC, a maior parte das exporta\u00e7\u00f5es do Mercosul entram no Egito livre de al\u00edquotas;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>03 &#8211; Tratado de Livre Com\u00e9rcio entre Mercosul e Uni\u00e3o Europeia:<\/strong>\u00a0o documento que d\u00e1 in\u00edcio ao TCL entre Mercosul e Uni\u00e3o Europeia (UE) foi assinado em 2019. As negocia\u00e7\u00f5es s\u00e3o complexas e ainda est\u00e3o em andamento, pois envolvem diversas \u00e1reas, como marcos regulat\u00f3rios, tarifas alfandeg\u00e1rias, regras sanit\u00e1rias, propriedade intelectual e compras p\u00fablicas.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>04 &#8211; Tratado de Livre Com\u00e9rcio com a EFTA<\/strong>: em julho de 2019, o presidente da EFTA (Associa\u00e7\u00e3o Europeia de Livre Com\u00e9rcio), disse que o acordo entre os dois blocos estava na reta final. Meses mais tarde, o Mercosul anunciou que o acordo estava firmado.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Com tantos Acordos Internacionais e vantagens que tratamos aqui, <strong>ficou clara a import\u00e2ncia que o Mercosul tem para o Brasil e a sua rela\u00e7\u00e3o comercial com outros pa\u00edses do mundo! <\/strong>Al\u00e9m disso, saber sobre esse assunto \u00e9 uma excelente maneira de encontrar novas oportunidades de neg\u00f3cio, seja com os pa\u00edses membros do bloco econ\u00f4mico, ou com as demais na\u00e7\u00f5es que possuem um TLC com o Mercosul.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Continue informado<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Gostou desse conte\u00fado? Ent\u00e3o continue conectado com a gente atrav\u00e9s da nossa <strong><a href=\"https:\/\/materiais.mastersul.com.br\/cadastro-newsletter\">Newsletter.<\/a><\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Semanalmente, enviamos no seu e-mail um resumo com os principais destaques do Com\u00e9rcio Exterior, al\u00e9m de compartilhar materiais exclusivos sobre os mais diversos temas. <a href=\"https:\/\/materiais.mastersul.com.br\/cadastro-newsletter\"><strong>Clique aqui para se cadastrar.<\/strong><\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>No dia 26 de mar\u00e7o de 1991, o Tratado de Assun\u00e7\u00e3o, que deu origem ao Mercado Comum do Sul, foi assinado pelos pa\u00edses: Argentina, Brasil, Paraguai e Uruguai. De l\u00e1 para c\u00e1, muita coisa aconteceu: acordos comerciais foram assinados, encontros diplom\u00e1ticos foram realizados, al\u00e9m de outros pa\u00edses come\u00e7arem a prestar aten\u00e7\u00e3o no bloco econ\u00f4mico formado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2127,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul\" \/>\n<meta property=\"og:description\" content=\"No dia 26 de mar\u00e7o de 1991, o Tratado de Assun\u00e7\u00e3o, que deu origem ao Mercado Comum do Sul, foi assinado pelos pa\u00edses: Argentina, Brasil, Paraguai e Uruguai. De l\u00e1 para c\u00e1, muita coisa aconteceu: acordos comerciais foram assinados, encontros diplom\u00e1ticos foram realizados, al\u00e9m de outros pa\u00edses come\u00e7arem a prestar aten\u00e7\u00e3o no bloco econ\u00f4mico formado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-06T00:53:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T13:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/Mercosul_-_Linkedin.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Amarante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Amarante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/\"},\"author\":{\"name\":\"Gabriel Amarante\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"headline\":\"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul\",\"datePublished\":\"2021-11-06T00:53:30+00:00\",\"dateModified\":\"2022-11-09T13:47:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/\"},\"wordCount\":985,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Mercosul_-_Linkedin.png\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/\",\"name\":\"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Mercosul_-_Linkedin.png\",\"datePublished\":\"2021-11-06T00:53:30+00:00\",\"dateModified\":\"2022-11-09T13:47:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Mercosul_-_Linkedin.png\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Mercosul_-_Linkedin.png\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\",\"name\":\"Gabriel Amarante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"caption\":\"Gabriel Amarante\"},\"sameAs\":[\"https:\\\/\\\/gabrielfreelancer.com.br\"],\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/amarante\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul[:] - Mastersul","og_description":"No dia 26 de mar\u00e7o de 1991, o Tratado de Assun\u00e7\u00e3o, que deu origem ao Mercado Comum do Sul, foi assinado pelos pa\u00edses: Argentina, Brasil, Paraguai e Uruguai. De l\u00e1 para c\u00e1, muita coisa aconteceu: acordos comerciais foram assinados, encontros diplom\u00e1ticos foram realizados, al\u00e9m de outros pa\u00edses come\u00e7arem a prestar aten\u00e7\u00e3o no bloco econ\u00f4mico formado [&hellip;]","og_url":"https:\/\/mastersul.com.br\/en\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/","og_site_name":"Mastersul","article_published_time":"2021-11-06T00:53:30+00:00","article_modified_time":"2022-11-09T13:47:30+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/Mercosul_-_Linkedin.png","type":"image\/png"}],"author":"Gabriel Amarante","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gabriel Amarante","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/"},"author":{"name":"Gabriel Amarante","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"headline":"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul","datePublished":"2021-11-06T00:53:30+00:00","dateModified":"2022-11-09T13:47:30+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/"},"wordCount":985,"commentCount":0,"image":{"@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/Mercosul_-_Linkedin.png","articleSection":["Sem categoria"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/","url":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/","name":"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/Mercosul_-_Linkedin.png","datePublished":"2021-11-06T00:53:30+00:00","dateModified":"2022-11-09T13:47:30+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"breadcrumb":{"@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/Mercosul_-_Linkedin.png","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/Mercosul_-_Linkedin.png","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/saiba-tudo-sobre-a-relacao-entre-brasil-e-mercosul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Saiba tudo sobre a rela\u00e7\u00e3o entre Brasil e Mercosul"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83","name":"Gabriel Amarante","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","caption":"Gabriel Amarante"},"sameAs":["https:\/\/gabrielfreelancer.com.br"],"url":"https:\/\/mastersul.com.br\/en\/author\/amarante\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/2126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=2126"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/2126\/revisions"}],"predecessor-version":[{"id":2143,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/2126\/revisions\/2143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/2127"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=2126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=2126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=2126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}