{"id":2653,"date":"2023-01-05T17:22:32","date_gmt":"2023-01-05T20:22:32","guid":{"rendered":"https:\/\/mastersul.com.br\/?p=2653"},"modified":"2023-01-05T17:22:32","modified_gmt":"2023-01-05T20:22:32","slug":"saiba-os-3-principais-assuntos-de-2023-para-o-comex","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/","title":{"rendered":"Saiba os 3 principais assuntos de 2023 para o Comex"},"content":{"rendered":"<p>J\u00e1 sabe o que esperar de 2023?<\/p>\n<p>Pois \u00e9, um novo ano sempre tem aquele gostinho de coisa nova e no Comex n\u00e3o \u00e9 diferente. Pensando nisso, pedimos aos nossos especialistas para definir quais s\u00e3o os tr\u00eas principais assuntos que devem pautar o ano de 2023 para o Com\u00e9rcio Exterior. Confira:<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>1 &#8211; (Des)Globaliza\u00e7\u00e3o<\/strong><\/h4>\n<p>Sim, voc\u00ea n\u00e3o leu errado! A competi\u00e7\u00e3o entre super pot\u00eancias como China e Estados Unidos leva diversos pa\u00edses do mundo a priorizarem uma economia mais fechada.<\/p>\n<p>Existe um certo receio de compartilhar tecnologias que possam fortalecer o mercado do pa\u00eds concorrente.<\/p>\n<p>Portanto, esse ser\u00e1 um dos maiores desafios para o Comex nos pr\u00f3ximos anos: entrar e permanecer como parceiro comercial de outros pa\u00edses.<\/p>\n<p>Em contrapartida, esse comportamento tamb\u00e9m pode influenciar a cria\u00e7\u00e3o de novos blocos econ\u00f4micos. Isso pode ser visto como uma grande vantagem para pa\u00edses como o Brasil, de entrarem de vez na participa\u00e7\u00e3o internacional como protagonistas no com\u00e9rcio internacional de mercadorias.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-2654\" src=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/025f29a640db04a067d7a540a7b4d004-300x225.gif\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/025f29a640db04a067d7a540a7b4d004-300x225.gif 300w, https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/025f29a640db04a067d7a540a7b4d004-768x576.gif 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4><strong>2 &#8211; Energia limpa<\/strong><\/h4>\n<p>Outro fator de alto impacto para as negocia\u00e7\u00f5es comerciais \u00e9 a fonte de energia.<\/p>\n<p>Com a imin\u00eancia da IMO 2023, os armadores do mundo est\u00e3o alterando seus servi\u00e7os para navios movidos a energia limpa.<\/p>\n<p>A transi\u00e7\u00e3o energ\u00e9tica para fontes mais limpas \u00e9 um dos temas que, com certeza, vai influenciar as opera\u00e7\u00f5es internacionais no mundo, n\u00e3o somente nos valores, mas tamb\u00e9m no modelo de neg\u00f3cio das empresas. Nunca foi t\u00e3o importante possuir parceiros que estejam preocupados com a sustentabilidade nos neg\u00f3cios.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-2655\" src=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/cf6b0dacc677edb546f82a225fd009c8-300x300.gif\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/cf6b0dacc677edb546f82a225fd009c8-300x300.gif 300w, https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/cf6b0dacc677edb546f82a225fd009c8-150x150.gif 150w, https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/cf6b0dacc677edb546f82a225fd009c8-100x100.gif 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4><strong>3 &#8211; Moeda unificada<\/strong><\/h4>\n<p>A guerra entre R\u00fassia e Ucr\u00e2nia levantou uma s\u00e9rie de questionamentos, um deles foi o sistema o financeiro,<\/p>\n<p>Por ter invadido o pa\u00eds ucraniano, a R\u00fassia foi exclu\u00edda do Sistema Swift e isso revelou ao mundo o quando a geopol\u00edtica colide com o sistema financeiro.<\/p>\n<p>Desse modo, para superar as barreiras impostas por esse sistema internacional de pagamentos, os cripto ativos v\u00eam ganhando espa\u00e7o. Afinal, al\u00e9m de serem neutros, d\u00e3o alternativa para levar e retirar dinheiro do pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 sabe o que esperar de 2023? Pois \u00e9, um novo ano sempre tem aquele gostinho de coisa nova e no Comex n\u00e3o \u00e9 diferente. Pensando nisso, pedimos aos nossos especialistas para definir quais s\u00e3o os tr\u00eas principais assuntos que devem pautar o ano de 2023 para o Com\u00e9rcio Exterior. Confira: &nbsp; 1 &#8211; (Des)Globaliza\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2658,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[],"class_list":["post-2653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saiba os 3 principais assuntos de 2023 para o Comex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba os 3 principais assuntos de 2023 para o Comex\" \/>\n<meta property=\"og:description\" content=\"J\u00e1 sabe o que esperar de 2023? Pois \u00e9, um novo ano sempre tem aquele gostinho de coisa nova e no Comex n\u00e3o \u00e9 diferente. Pensando nisso, pedimos aos nossos especialistas para definir quais s\u00e3o os tr\u00eas principais assuntos que devem pautar o ano de 2023 para o Com\u00e9rcio Exterior. Confira: &nbsp; 1 &#8211; (Des)Globaliza\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-05T20:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/Redes-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Equipe Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/\"},\"author\":{\"name\":\"Equipe Marketing\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"headline\":\"Saiba os 3 principais assuntos de 2023 para o Comex\",\"datePublished\":\"2023-01-05T20:22:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/\"},\"wordCount\":369,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Blog.png\",\"articleSection\":[\"Artigo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/\",\"name\":\"Saiba os 3 principais assuntos de 2023 para o Comex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Blog.png\",\"datePublished\":\"2023-01-05T20:22:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Blog.png\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Blog.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saiba os 3 principais assuntos de 2023 para o Comex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\",\"name\":\"Equipe Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"caption\":\"Equipe Marketing\"},\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/mastersul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saiba os 3 principais assuntos de 2023 para o Comex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]Saiba os 3 principais assuntos de 2023 para o Comex[:] - Mastersul","og_description":"J\u00e1 sabe o que esperar de 2023? Pois \u00e9, um novo ano sempre tem aquele gostinho de coisa nova e no Comex n\u00e3o \u00e9 diferente. Pensando nisso, pedimos aos nossos especialistas para definir quais s\u00e3o os tr\u00eas principais assuntos que devem pautar o ano de 2023 para o Com\u00e9rcio Exterior. Confira: &nbsp; 1 &#8211; (Des)Globaliza\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/mastersul.com.br\/en\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/","og_site_name":"Mastersul","article_published_time":"2023-01-05T20:22:32+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/Redes-1024x576.png","type":"image\/png"}],"author":"Equipe Marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe Marketing","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/"},"author":{"name":"Equipe Marketing","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"headline":"Saiba os 3 principais assuntos de 2023 para o Comex","datePublished":"2023-01-05T20:22:32+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/"},"wordCount":369,"commentCount":0,"image":{"@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/Blog.png","articleSection":["Artigo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/","url":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/","name":"Saiba os 3 principais assuntos de 2023 para o Comex","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/Blog.png","datePublished":"2023-01-05T20:22:32+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"breadcrumb":{"@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/Blog.png","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2023\/01\/Blog.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/saiba-os-3-principais-assuntos-de-2023-para-o-comex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Saiba os 3 principais assuntos de 2023 para o Comex"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665","name":"Equipe Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","caption":"Equipe Marketing"},"url":"https:\/\/mastersul.com.br\/en\/author\/mastersul\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/2653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=2653"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/2653\/revisions"}],"predecessor-version":[{"id":2656,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/2653\/revisions\/2656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/2658"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=2653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=2653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=2653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}