{"id":3689,"date":"2024-07-22T14:56:13","date_gmt":"2024-07-22T17:56:13","guid":{"rendered":"https:\/\/mastersul.com.br\/?p=3689"},"modified":"2024-07-22T15:44:04","modified_gmt":"2024-07-22T18:44:04","slug":"rfb-aperfeicoa-normas-do-programa-oea","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/rfb-aperfeicoa-normas-do-programa-oea\/","title":{"rendered":"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA"},"content":{"rendered":"<p>A Receita Federal publicou a Instru\u00e7\u00e3o Normativa RFB n\u00ba 2.200, de 12 de julho de 2024, que altera a IN RFB n\u00ba 2.154 do Programa Brasileiro de Operador Econ\u00f4mico Autorizado (Programa OEA). Essas mudan\u00e7as visam aprimorar o programa, garantindo maior transpar\u00eancia, confian\u00e7a e coopera\u00e7\u00e3o.<\/p>\n<p><strong>Principais altera\u00e7\u00f5es na aplicabilidade dos Novos Requisitos<br \/>\n<\/strong><br \/>\nA partir de 1\u00ba de agosto de 2024, a an\u00e1lise de certifica\u00e7\u00e3o ser\u00e1 baseada nos requisitos da Portaria Coana n\u00ba 77 de 2020 para requerimentos protocolados at\u00e9 31 de julho de 2024. Esta medida busca assegurar maior seguran\u00e7a jur\u00eddica aos intervenientes, evitando preju\u00edzos devido a poss\u00edveis atrasos nos processos de certifica\u00e7\u00e3o.<br \/>\nAl\u00e9m disso, a IN RFB n\u00ba 2.200 amplia o prazo de transi\u00e7\u00e3o para empresas j\u00e1 certificadas no Programa OEA. Essas empresas passar\u00e3o a ser monitoradas pelos novos requisitos a partir de 1\u00ba de janeiro de 2025, proporcionando tempo adequado para que realizem as devidas adequa\u00e7\u00f5es internas.<\/p>\n<p><strong>Harmoniza\u00e7\u00e3o do procedimento de julgamento de Recursos Administrativos<br \/>\n<\/strong><br \/>\nOutro ponto importante \u00e9 a harmoniza\u00e7\u00e3o do procedimento de julgamento de recursos administrativos contra indeferimentos. Assim como no rito de exclus\u00e3o, recursos contra indeferimentos ser\u00e3o analisados por uma equipe diferente daquela que proferiu a decis\u00e3o inicial. Esta medida, conforme preconiza a Conven\u00e7\u00e3o de Quioto Revisada, assegura a imparcialidade e independ\u00eancia necess\u00e1rias aos processos de julgamento de recursos administrativos.<\/p>\n<p><strong>Exclus\u00e3o volunt\u00e1ria do Programa OEA<br \/>\n<\/strong><br \/>\nFoi introduzida a possibilidade de solicita\u00e7\u00e3o de exclus\u00e3o do Programa OEA a pedido do interveniente, podendo ser efetuada a qualquer momento. Esta altera\u00e7\u00e3o refor\u00e7a o car\u00e1ter volunt\u00e1rio da participa\u00e7\u00e3o no Programa.<\/p>\n<p><strong>Altera\u00e7\u00f5es na Portaria Coana n\u00ba 133<br \/>\n<\/strong><br \/>\nA Portaria Coana n\u00ba 133, que regulamenta dispositivos da IN RFB n\u00ba 2.154, foi alterada pela Portaria Coana n\u00ba 155, de 10 de julho de 2024, para refletir as mudan\u00e7as trazidas pela IN RFB n\u00ba 2.200. Entre as altera\u00e7\u00f5es, destacam-se:<\/p>\n<p><strong>&#8211;<\/strong>Compartilhamento de Dados<\/p>\n<p>Inclus\u00e3o, no item 3 do Anexo I, da possibilidade de compartilhamento das informa\u00e7\u00f5es do ponto de contato do interveniente (nome e e-mail) com os \u00f3rg\u00e3os participantes do Programa OEA-Integrado.<\/p>\n<p><strong>&#8211;<\/strong>Requisitos no Anexo II<strong><br \/>\n<\/strong><br \/>\nExclus\u00e3o dos requisitos 8.7, 8.8 e 8.9, j\u00e1 contemplados em outros requisitos e no art. 17 da IN RFB n\u00ba 2.154.<br \/>\nInclus\u00e3o do requisito 15.5, anteriormente ausente devido a um erro de publica\u00e7\u00e3o.<br \/>\nAltera\u00e7\u00e3o do requisito 13.9, direcionando sua aplicabilidade ao pr\u00f3prio interveniente, em vez de empresas parceiras.<\/p>\n<p><strong>&#8211;<\/strong>Altera\u00e7\u00f5es no Anexo III<\/p>\n<p>Para empresas de grande porte com v\u00e1rias unidades operacionais, o interveniente deve informar em qual unidade est\u00e1 sediada a equipe ou setor que atua no com\u00e9rcio exterior (despacho aduaneiro, log\u00edstica, contrata\u00e7\u00e3o de transporte internacional, etc.).<br \/>\nEsta informa\u00e7\u00e3o \u00e9 essencial para a distribui\u00e7\u00e3o do requerimento entre as EqOEA e para o planejamento das valida\u00e7\u00f5es ou revalida\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal publicou a Instru\u00e7\u00e3o Normativa RFB n\u00ba 2.200, de 12 de julho de 2024, que altera a IN RFB n\u00ba 2.154 do Programa Brasileiro de Operador Econ\u00f4mico Autorizado (Programa OEA). Essas mudan\u00e7as visam aprimorar o programa, garantindo maior transpar\u00eancia, confian\u00e7a e coopera\u00e7\u00e3o. Principais altera\u00e7\u00f5es na aplicabilidade dos Novos Requisitos A partir de 1\u00ba [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[],"class_list":["post-3689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA<\/title>\n<meta name=\"description\" content=\"Mudan\u00e7as no Programa OEA: leia nosso artigo completo e fique por dentro das mudan\u00e7as que garantem maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e efici\u00eancia no Programa OEA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/rfb-aperfeicoa-normas-do-programa-oea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA\" \/>\n<meta property=\"og:description\" content=\"Mudan\u00e7as no Programa OEA: leia nosso artigo completo e fique por dentro das mudan\u00e7as que garantem maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e efici\u00eancia no Programa OEA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/rfb-aperfeicoa-normas-do-programa-oea\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T17:56:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T18:44:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/07\/50537433-b22f-4d45-b13b-d394a0b83b1f.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"276\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Equipe Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/\"},\"author\":{\"name\":\"Equipe Marketing\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"headline\":\"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA\",\"datePublished\":\"2024-07-22T17:56:13+00:00\",\"dateModified\":\"2024-07-22T18:44:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/\"},\"wordCount\":475,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/50537433-b22f-4d45-b13b-d394a0b83b1f.png\",\"articleSection\":[\"Artigo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/\",\"name\":\"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/50537433-b22f-4d45-b13b-d394a0b83b1f.png\",\"datePublished\":\"2024-07-22T17:56:13+00:00\",\"dateModified\":\"2024-07-22T18:44:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"description\":\"Mudan\u00e7as no Programa OEA: leia nosso artigo completo e fique por dentro das mudan\u00e7as que garantem maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e efici\u00eancia no Programa OEA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/50537433-b22f-4d45-b13b-d394a0b83b1f.png\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/50537433-b22f-4d45-b13b-d394a0b83b1f.png\",\"width\":768,\"height\":276},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/rfb-aperfeicoa-normas-do-programa-oea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\",\"name\":\"Equipe Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"caption\":\"Equipe Marketing\"},\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/mastersul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA","description":"Mudan\u00e7as no Programa OEA: leia nosso artigo completo e fique por dentro das mudan\u00e7as que garantem maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e efici\u00eancia no Programa OEA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/rfb-aperfeicoa-normas-do-programa-oea\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA[:] - Mastersul","og_description":"[:pt]Mudan\u00e7as no Programa OEA: leia nosso artigo completo e fique por dentro das mudan\u00e7as que garantem maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e efici\u00eancia no Programa OEA.[:]","og_url":"https:\/\/mastersul.com.br\/en\/rfb-aperfeicoa-normas-do-programa-oea\/","og_site_name":"Mastersul","article_published_time":"2024-07-22T17:56:13+00:00","article_modified_time":"2024-07-22T18:44:04+00:00","og_image":[{"width":768,"height":276,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/07\/50537433-b22f-4d45-b13b-d394a0b83b1f.png","type":"image\/png"}],"author":"Equipe Marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe Marketing","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/"},"author":{"name":"Equipe Marketing","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"headline":"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA","datePublished":"2024-07-22T17:56:13+00:00","dateModified":"2024-07-22T18:44:04+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/"},"wordCount":475,"image":{"@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/07\/50537433-b22f-4d45-b13b-d394a0b83b1f.png","articleSection":["Artigo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/","url":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/","name":"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/07\/50537433-b22f-4d45-b13b-d394a0b83b1f.png","datePublished":"2024-07-22T17:56:13+00:00","dateModified":"2024-07-22T18:44:04+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"description":"Mudan\u00e7as no Programa OEA: leia nosso artigo completo e fique por dentro das mudan\u00e7as que garantem maior seguran\u00e7a jur\u00eddica, transpar\u00eancia e efici\u00eancia no Programa OEA.","breadcrumb":{"@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/07\/50537433-b22f-4d45-b13b-d394a0b83b1f.png","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/07\/50537433-b22f-4d45-b13b-d394a0b83b1f.png","width":768,"height":276},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/rfb-aperfeicoa-normas-do-programa-oea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Receita Federal aperfei\u00e7oa disposi\u00e7\u00f5es do Programa OEA"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665","name":"Equipe Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","caption":"Equipe Marketing"},"url":"https:\/\/mastersul.com.br\/en\/author\/mastersul\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/3689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=3689"}],"version-history":[{"count":2,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/3689\/revisions"}],"predecessor-version":[{"id":3693,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/3689\/revisions\/3693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/3690"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=3689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=3689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=3689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}