{"id":3833,"date":"2024-09-09T11:37:01","date_gmt":"2024-09-09T14:37:01","guid":{"rendered":"https:\/\/mastersul.com.br\/?p=3833"},"modified":"2024-09-09T11:41:24","modified_gmt":"2024-09-09T14:41:24","slug":"artigo_classificacao_fiscal_anel_superbowl-10-09-24","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/","title":{"rendered":"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica"},"content":{"rendered":"<p>Pela primeira vez na hist\u00f3ria, o Brasil foi palco de uma partida da NFL. Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL &#8211; e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.<\/p>\n<p>Todo ano, as franquias da NFL competem pelo cobi\u00e7ado trof\u00e9u do Super Bowl. Al\u00e9m da gl\u00f3ria e da premia\u00e7\u00e3o em dinheiro, os vencedores recebem um s\u00edmbolo de conquista inigual\u00e1vel: o anel do Super Bowl. Cada anel \u00e9 \u00fanico, com design exclusivo para cada edi\u00e7\u00e3o, e produzido com materiais preciosos como ouro e diamantes. Isso nos leva a uma interessante reflex\u00e3o: se esses an\u00e9is fossem importados para o Brasil, qual seria a classifica\u00e7\u00e3o fiscal ideal?<\/p>\n<p><strong>O anel do Super Bowl \u00e9 um Trof\u00e9u ou uma Joia?<\/strong><\/p>\n<p>Vamos come\u00e7ar pelo b\u00e1sico: um anel do Super Bowl pode ser considerado um trof\u00e9u? Afinal, a defini\u00e7\u00e3o de &#8220;trof\u00e9u&#8221; \u00e9 um item entregue ao vencedor de uma competi\u00e7\u00e3o. No entanto, a posi\u00e7\u00e3o NCM 8306, que se refere a &#8220;objetos de ornamenta\u00e7\u00e3o de metais comuns&#8221;, n\u00e3o se aplica aqui, uma vez que esses an\u00e9is s\u00e3o feitos de metais preciosos e n\u00e3o de metais comuns. Sendo assim, o anel n\u00e3o \u00e9 classificado como trof\u00e9u, mas sim como uma joia.<\/p>\n<p><strong>Joia de Metal Precioso ou de Pedra Preciosa?<\/strong><\/p>\n<p>Agora que estabelecemos que o anel \u00e9 uma joia, precisamos identificar se ele deve ser classificado como uma joia de metal precioso (NCM 7113) ou uma joia de pedra preciosa (NCM 7116). No caso do anel do Kansas City Chiefs, por exemplo, ele \u00e9 composto por 529 diamantes, 38 rubis e 14,8 quilates de pedras preciosas, montados em uma base de ouro branco de 14 quilates.<\/p>\n<p>Uma interpreta\u00e7\u00e3o poss\u00edvel seria classific\u00e1-lo sob o c\u00f3digo NCM 7116.20.10, que cobre joias de pedra preciosa, j\u00e1 que as pedras preciosas dominam o design e o valor da pe\u00e7a. Se removermos os diamantes, o que restaria seria um anel simples de ouro branco.<\/p>\n<p>Por outro lado, poder\u00edamos argumentar que o ouro branco \u00e9 o material principal que define a pe\u00e7a como um anel. Sem o ouro branco, ter\u00edamos apenas pedras preciosas sem forma ou utilidade como joia. Portanto, a melhor classifica\u00e7\u00e3o seria a de uma joia de metal precioso incrustada com pedras preciosas, conforme o c\u00f3digo NCM 7113.19.00.<\/p>\n<p><strong>Conclus\u00e3o: A Classifica\u00e7\u00e3o Ideal<\/strong><\/p>\n<p>Ap\u00f3s uma an\u00e1lise detalhada, conclu\u00edmos que o c\u00f3digo NCM 7113.19.00 \u00e9 o mais adequado para a classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl. Isso porque, apesar de o brilho e o valor das pedras preciosas serem impressionantes, o ouro branco \u00e9 a estrutura que sustenta e define a pe\u00e7a como um anel. Assim, a joia deve ser classificada como um produto de metal precioso com pedras preciosas, e n\u00e3o o contr\u00e1rio.<\/p>\n<p>Essa an\u00e1lise, al\u00e9m de fascinante, revela a complexidade envolvida na classifica\u00e7\u00e3o de itens de luxo no com\u00e9rcio exterior, destacando a import\u00e2ncia de uma avalia\u00e7\u00e3o criteriosa para garantir a correta tributa\u00e7\u00e3o e regulamenta\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pela primeira vez na hist\u00f3ria, o Brasil foi palco de uma partida da NFL. Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL &#8211; e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal. Todo ano, as franquias da NFL competem pelo cobi\u00e7ado trof\u00e9u [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[10],"tags":[],"class_list":["post-3833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica<\/title>\n<meta name=\"description\" content=\"Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL - e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica\" \/>\n<meta property=\"og:description\" content=\"Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL - e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T14:37:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T14:41:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/09\/r659700_1296x729_16-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"729\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/\"},\"author\":{\"name\":\"Equipe Marketing\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"headline\":\"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica\",\"datePublished\":\"2024-09-09T14:37:01+00:00\",\"dateModified\":\"2024-09-09T14:41:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/\"},\"wordCount\":544,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/r659700_1296x729_16-9.jpg\",\"articleSection\":[\"Artigo\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/\",\"name\":\"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/r659700_1296x729_16-9.jpg\",\"datePublished\":\"2024-09-09T14:37:01+00:00\",\"dateModified\":\"2024-09-09T14:41:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"description\":\"Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL - e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/r659700_1296x729_16-9.jpg\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/r659700_1296x729_16-9.jpg\",\"width\":1296,\"height\":729},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\",\"name\":\"Equipe Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"caption\":\"Equipe Marketing\"},\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/mastersul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica","description":"Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL - e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica[:] - Mastersul","og_description":"[:pt]Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL - e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.[:]","og_url":"https:\/\/mastersul.com.br\/en\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/","og_site_name":"Mastersul","article_published_time":"2024-09-09T14:37:01+00:00","article_modified_time":"2024-09-09T14:41:24+00:00","og_image":[{"width":1296,"height":729,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/09\/r659700_1296x729_16-9.jpg","type":"image\/jpeg"}],"author":"Equipe Marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe Marketing","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/"},"author":{"name":"Equipe Marketing","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"headline":"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica","datePublished":"2024-09-09T14:37:01+00:00","dateModified":"2024-09-09T14:41:24+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/"},"wordCount":544,"image":{"@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/09\/r659700_1296x729_16-9.jpg","articleSection":["Artigo"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/","url":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/","name":"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/09\/r659700_1296x729_16-9.jpg","datePublished":"2024-09-09T14:37:01+00:00","dateModified":"2024-09-09T14:41:24+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"description":"Por aqui, enxergamos o Com\u00e9rcio Exterior em todas as coisas -inclusive em uma partida do NFL - e, por isso, trouxemos uma an\u00e1lise do evento sob a perspectiva da classifica\u00e7\u00e3o fiscal.","breadcrumb":{"@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/09\/r659700_1296x729_16-9.jpg","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2024\/09\/r659700_1296x729_16-9.jpg","width":1296,"height":729},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/artigo_classificacao_fiscal_anel_superbowl-10-09-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Classifica\u00e7\u00e3o fiscal dos an\u00e9is do Super Bowl: uma an\u00e1lise curiosa e estrat\u00e9gica"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665","name":"Equipe Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","caption":"Equipe Marketing"},"url":"https:\/\/mastersul.com.br\/en\/author\/mastersul\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/3833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=3833"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/3833\/revisions"}],"predecessor-version":[{"id":3835,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/3833\/revisions\/3835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/3834"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=3833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=3833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=3833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}