{"id":4527,"date":"2025-08-04T10:49:57","date_gmt":"2025-08-04T13:49:57","guid":{"rendered":"https:\/\/mastersul.com.br\/?p=4527"},"modified":"2025-08-04T10:49:57","modified_gmt":"2025-08-04T13:49:57","slug":"mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/en\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/","title":{"rendered":"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda"},"content":{"rendered":"<h4><b>01 &#8211; Novas al\u00edquotas para carros el\u00e9tricos e h\u00edbridos<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Desde 1\u00ba de julho de 2025, o governo brasileiro reajustou os impostos de importa\u00e7\u00e3o sobre todos os ve\u00edculos eletrificados: os el\u00e9tricos (BEV) passaram de 18\u202f% para 25\u202f%, os h\u00edbridos plug\u2011in (PHEV) de 20\u202f% para 28\u202f%, e os h\u00edbridos convencionais (HEV) de 25\u202f% para 30\u202f%, conforme cronograma do MDIC. Esse plano prev\u00ea que, em julho de 2026, todas as categorias ter\u00e3o al\u00edquota uniforme de 35\u202f%.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A antecipa\u00e7\u00e3o parcial da press\u00e3o fiscal tamb\u00e9m atingiu os caminh\u00f5es el\u00e9tricos e h\u00edbridos desmontados (CKD). A partir de janeiro de 2027, esses ve\u00edculos recolher\u00e3o a al\u00edquota m\u00e1xima, reduzindo o prazo original de julho de 2028, atendendo a uma solicita\u00e7\u00e3o da Anfavea. Antes disso, uma cota de US$\u202f463 milh\u00f5es com al\u00edquota zero estar\u00e1 vigente por seis meses para CKD e SKD.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A medida atende parcialmente \u00e0 press\u00e3o de montadoras nacionais (\u201cdinossauros\u201d, como GM, VW, Stellantis, Toyota) que concorrem com a chinesa BYD, que buscava redu\u00e7\u00e3o de impostos para facilitar seu in\u00edcio de opera\u00e7\u00f5es em Cama\u00e7ari (BA). Os fabricantes sediados no Brasil apoiaram a limita\u00e7\u00e3o das isen\u00e7\u00f5es e a antecipa\u00e7\u00e3o do cronograma para fortalecer a produ\u00e7\u00e3o interna.<\/span><\/p>\n<h4><b>02 &#8211; EUA isentam 694 produtos brasileiros da tarifa de 50\u202f%<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Em 30 de julho de 2025, o presidente dos Estados Unidos assinou uma Ordem Executiva que aplica tarifa de 50\u202f% sobre diversos produtos importados do Brasil, com entrada em vigor em 6 de agosto de 2025. A medida \u00e9 parte de uma estrat\u00e9gia mais ampla de prote\u00e7\u00e3o da ind\u00fastria americana e tens\u00e3o comercial com o Brasil.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar disso, 694 produtos brasileiros foram exclu\u00eddos da tributa\u00e7\u00e3o, entre eles suco e polpa de laranja, combust\u00edveis, min\u00e9rios, fertilizantes, celulose, aeronaves civis e metais preciosos. Esses itens foram considerados \u201cinteresse nacional\u201d para os EUA, justificando a isen\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, produtos n\u00e3o isentos, como caf\u00e9, frutas frescas, carnes e cacau, ser\u00e3o tributados em 50\u202f%, o que poder\u00e1 afetar fortemente a competitividade desses setores no mercado norte\u2011americano. Especialistas do agroneg\u00f3cio alertam para poss\u00edvel retra\u00e7\u00e3o nas exporta\u00e7\u00f5es j\u00e1 no segundo semestre de 2025, especialmente para caf\u00e9 e carne.<\/span><\/p>\n<h4><b>03 &#8211; Corrente de com\u00e9rcio do Brasil cresce 6,6\u202f% em julho<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Dados parciais da quarta semana de julho de 2025 mostram que a corrente de com\u00e9rcio brasileira cresceu 6,6\u202f%, alcan\u00e7ando aproximadamente US$\u202f47,7\u202fbilh\u00f5es no m\u00eas, em compara\u00e7\u00e3o ao mesmo per\u00edodo de 2024. As exporta\u00e7\u00f5es somaram US$\u202f26,2\u202fbilh\u00f5es (+3,0\u202f%) e as importa\u00e7\u00f5es US$\u202f21,4\u202fbilh\u00f5es (+11,5\u202f%).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No saldo, o super\u00e1vit da balan\u00e7a comercial ficou em US$\u202f4,8\u202fbilh\u00f5es, apesar de representar queda de 23,2\u202f% em rela\u00e7\u00e3o a julho de 2024. No acumulado de janeiro a julho de 2025, o com\u00e9rcio exterior totalizou US$\u202f349\u202fbilh\u00f5es, com exporta\u00e7\u00f5es de US$\u202f192,1\u202fbilh\u00f5es e importa\u00e7\u00f5es de US$\u202f157,2\u202fbilh\u00f5es, resultando em super\u00e1vit de US$\u202f34,9\u202fbilh\u00f5es e alta de 5,1\u202f% na corrente comercial anual.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por setores, a Ind\u00fastria de Transforma\u00e7\u00e3o liderou o crescimento tanto em exporta\u00e7\u00e3o quanto em importa\u00e7\u00e3o, com alta de 8,1\u202f% nas vendas internacionais e 13,7\u202f% nas compras externas. A Agropecu\u00e1ria registrou expans\u00e3o modesta nas exporta\u00e7\u00f5es (+2,4\u202f%) e importa\u00e7\u00f5es (+5,4\u202f%), enquanto a Ind\u00fastria Extrativa apresentou queda nas exporta\u00e7\u00f5es (\u22127,6\u202f%) e reduziu tamb\u00e9m as importa\u00e7\u00f5es (\u221217,2\u202f%).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 &#8211; Novas al\u00edquotas para carros el\u00e9tricos e h\u00edbridos Desde 1\u00ba de julho de 2025, o governo brasileiro reajustou os impostos de importa\u00e7\u00e3o sobre todos os ve\u00edculos eletrificados: os el\u00e9tricos (BEV) passaram de 18\u202f% para 25\u202f%, os h\u00edbridos plug\u2011in (PHEV) de 20\u202f% para 28\u202f%, e os h\u00edbridos convencionais (HEV) de 25\u202f% para 30\u202f%, conforme cronograma [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[],"class_list":["post-4527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda<\/title>\n<meta name=\"description\" content=\"O mercado de carros eletrificados acompanha novos reajustes de al\u00edquotas. Veja tamb\u00e9m o que acontece nos produtos taxados pelos EUA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/en\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"es\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda\" \/>\n<meta property=\"og:description\" content=\"O mercado de carros eletrificados acompanha novos reajustes de al\u00edquotas. Veja tamb\u00e9m o que acontece nos produtos taxados pelos EUA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/en\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T13:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/08\/AdobeStock_79753939.png\" \/>\n\t<meta property=\"og:image:width\" content=\"602\" \/>\n\t<meta property=\"og:image:height\" content=\"402\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Equipe Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/\"},\"author\":{\"name\":\"Equipe Marketing\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"headline\":\"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda\",\"datePublished\":\"2025-08-04T13:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/\"},\"wordCount\":563,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_79753939.png\",\"articleSection\":[\"Informa\u00e7\u00e3o\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/\",\"name\":\"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_79753939.png\",\"datePublished\":\"2025-08-04T13:49:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"description\":\"O mercado de carros eletrificados acompanha novos reajustes de al\u00edquotas. Veja tamb\u00e9m o que acontece nos produtos taxados pelos EUA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_79753939.png\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_79753939.png\",\"width\":602,\"height\":402},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\",\"name\":\"Equipe Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"caption\":\"Equipe Marketing\"},\"url\":\"https:\\\/\\\/mastersul.com.br\\\/en\\\/author\\\/mastersul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda","description":"O mercado de carros eletrificados acompanha novos reajustes de al\u00edquotas. Veja tamb\u00e9m o que acontece nos produtos taxados pelos EUA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/en\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/","og_locale":"en_US","og_type":"article","og_title":"[:pt]Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda[:] - Mastersul","og_description":"[:pt]O mercado de carros eletrificados acompanha novos reajustes de al\u00edquotas. Veja tamb\u00e9m o que acontece nos produtos taxados pelos EUA.[:]","og_url":"https:\/\/mastersul.com.br\/en\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/","og_site_name":"Mastersul","article_published_time":"2025-08-04T13:49:57+00:00","og_image":[{"width":602,"height":402,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/08\/AdobeStock_79753939.png","type":"image\/png"}],"author":"Equipe Marketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Equipe Marketing","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/"},"author":{"name":"Equipe Marketing","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"headline":"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda","datePublished":"2025-08-04T13:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/"},"wordCount":563,"image":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/08\/AdobeStock_79753939.png","articleSection":["Informa\u00e7\u00e3o"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/","url":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/","name":"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/08\/AdobeStock_79753939.png","datePublished":"2025-08-04T13:49:57+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"description":"O mercado de carros eletrificados acompanha novos reajustes de al\u00edquotas. Veja tamb\u00e9m o que acontece nos produtos taxados pelos EUA.","breadcrumb":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/08\/AdobeStock_79753939.png","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/08\/AdobeStock_79753939.png","width":602,"height":402},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-novas-aliquotas-carros-eletricos-04-08-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Redu\u00e7\u00e3o de isen\u00e7\u00f5es em carros eletrificados: o que muda"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665","name":"Equipe Marketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","caption":"Equipe Marketing"},"url":"https:\/\/mastersul.com.br\/en\/author\/mastersul\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/4527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/comments?post=4527"}],"version-history":[{"count":2,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/4527\/revisions"}],"predecessor-version":[{"id":4530,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/posts\/4527\/revisions\/4530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media\/4528"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/media?parent=4527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/categories?post=4527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/en\/wp-json\/wp\/v2\/tags?post=4527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}