{"id":1881,"date":"2021-12-27T21:45:06","date_gmt":"2021-12-28T00:45:06","guid":{"rendered":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/"},"modified":"2022-11-10T15:08:33","modified_gmt":"2022-11-10T18:08:33","slug":"conheca-as-dicas-e-vantagem-de-importar-autopecas","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/es\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/","title":{"rendered":"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as"},"content":{"rendered":"<p>Voc\u00ea que trabalha com a comercializa\u00e7\u00e3o de autope\u00e7as j\u00e1 parou para pensar que vivemos no pa\u00eds que possui a quarta maior rede de estradas e rodovias do mundo? S\u00e3o mais de 1,8 milh\u00f5es de quil\u00f4metros de extens\u00e3o.<\/p>\n<p>De acordo com o IBGE, 61% do transporte de carga brasileira circula pelo asfalto. Mais da metade das viagens do pa\u00eds \u00e9 feita sobre rodas e, segundo a Associa\u00e7\u00e3o Brasileira das Empresas de Transporte Terrestre de Passageiros (ABRATI) 70% dos passageiros viajam de \u00f4nibus ou carro.<\/p>\n<p>Esses dados comprovam que no Brasil h\u00e1 um potencial enorme a ser explorado para quem trabalha com a ind\u00fastria automobil\u00edstica e um deles \u00e9 a importa\u00e7\u00e3o de autope\u00e7as.<\/p>\n<p>&nbsp;<\/p>\n<h4>COMO SE PREPARAR PARA IMPORTAR AUTOPE\u00c7AS<\/h4>\n<p>Na hora de avaliar a importa\u00e7\u00e3o como uma op\u00e7\u00e3o vi\u00e1vel \u00e9 preciso estar atento para alguns detalhes. Afinal, estar preparado \u00e9 essencial para o sucesso de uma opera\u00e7\u00e3o internacional. Confira 3 dicas para planejar a sua importa\u00e7\u00e3o de autope\u00e7as:<\/p>\n<p><strong>1- Confira as quest\u00f5es legais:<\/strong> Para importar \u00e9 necess\u00e1rio estar com a toda a documenta\u00e7\u00e3o legalizada perante a Receita Federal. Assim, voc\u00ea evita dores de cabe\u00e7a desnecess\u00e1rias durante seu processo internacional;<\/p>\n<p><strong>2- Conhe\u00e7a os impostos e taxas:<\/strong> A parte \u201cchata\u201d de uma importa\u00e7\u00e3o s\u00e3o os impostos que incidem sobre o valor final. \u00c9 necess\u00e1rio calcular todos os custos corretamente. Veja <a href=\"https:\/\/mastersul.com.br\/blog\/icms-sobre-importacao\/\">aqui<\/a> como fazer essa conta.<\/p>\n<p><strong>3- Conte com parceiros confi\u00e1veis:<\/strong> Utilizar os servi\u00e7os de uma assessoria de confian\u00e7a \u00e9 uma \u00f3tima alternativa para conseguir desenhar o processo de importa\u00e7\u00e3o de maneira inteligente e ainda estudar a viabilidade de empregar algum regime aduaneiro especial, a fim de reduzir os seus custos.<\/p>\n<p>&nbsp;<\/p>\n<h4>PORQUE IMPORTAR AUTOPE\u00c7AS?<\/h4>\n<p><strong>1- Mais economia:<\/strong> Algumas pe\u00e7as importadas podem sair at\u00e9 80% mais em conta do que as produzidas em solo nacional;<\/p>\n<p><strong>2- Vantagem competitiva:<\/strong> Com menor custo e mais qualidade no servi\u00e7o prestado (ou nas pe\u00e7as vendidas) voc\u00ea t\u00eam maior destaque no mercado e fica na frente dos seus concorrentes;<\/p>\n<p><strong>3- Variedade:<\/strong> com a exce\u00e7\u00e3o de algumas pe\u00e7as espec\u00edficas, como pneus e bateria que necessitam de regula\u00e7\u00e3o interna, todos os produtos automotivo podem ser importados.<br \/>\nAtualmente, existem diversos regimes especiais que podem facilitar esse processo de importa\u00e7\u00e3o, como o <a href=\"https:\/\/mastersul.com.br\/blog\/programa-rota-2030-mobilidade-e-logistica\/\">Rota 2030.<\/a>\u00a0Um programa espec\u00edfico para o setor o automobil\u00edstico, que reduz a al\u00edquota a zero para importa\u00e7\u00e3o de autope\u00e7as sem produ\u00e7\u00e3o equivalente no Brasil.<\/p>\n<p>A importa\u00e7\u00e3o de autope\u00e7as \u00e9 uma \u00f3tima op\u00e7\u00e3o para voc\u00ea que quer aprimorar seu neg\u00f3cio e se destacar nesse mercado.<\/p>\n<p>Se voc\u00ea est\u00e1 pensando em inovar o seu neg\u00f3cio de autope\u00e7as, mas tem d\u00favidas com rela\u00e7\u00e3o a documenta\u00e7\u00e3o e quer a opera\u00e7\u00e3o desenhada de forma eficiente, venha conversar com a gente! Contamos com uma equipe especializada pronta para oferecer as melhores solu\u00e7\u00f5es personalizadas para voc\u00ea: contato@mastersul.com | 41 3024 0100<\/p>\n<hr \/>\n<p>Acompanhe nossas \u00faltimas publica\u00e7\u00f5es:<\/p>\n<p>Conhe\u00e7a os 17 Regimes Aduaneiros que podem reduzir os seus custos &#8211; <a href=\"https:\/\/mastersul.com.br\/blog\/conheca-os-17-regimes-especiais-aduaneiros-que-podem-reduzir-os-seus-custos\/\">clique aqui<\/a><br \/>\nSaiba quais as mudan\u00e7as esperadas para os Incoterms 2020 &#8211; <a href=\"https:\/\/mastersul.com.br\/blog\/saiba-quais-sao-as-mudancas-esperadas-para-os-incoterms-2020\/\">clique aqui<\/a><br \/>\nPor que contratar um seguro internacional de cargas &#8211; <a href=\"https:\/\/mastersul.com.br\/blog\/por-que-contratar-um-seguro-internacional-de-cargas\/\">clique aqui<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea que trabalha com a comercializa\u00e7\u00e3o de autope\u00e7as j\u00e1 parou para pensar que vivemos no pa\u00eds que possui a quarta maior rede de estradas e rodovias do mundo? S\u00e3o mais de 1,8 milh\u00f5es de quil\u00f4metros de extens\u00e3o. De acordo com o IBGE, 61% do transporte de carga brasileira circula pelo asfalto. Mais da metade das [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1882,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/es\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea que trabalha com a comercializa\u00e7\u00e3o de autope\u00e7as j\u00e1 parou para pensar que vivemos no pa\u00eds que possui a quarta maior rede de estradas e rodovias do mundo? S\u00e3o mais de 1,8 milh\u00f5es de quil\u00f4metros de extens\u00e3o. De acordo com o IBGE, 61% do transporte de carga brasileira circula pelo asfalto. Mais da metade das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/es\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-28T00:45:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T18:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_importacao_de_autopecas_06_08_2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Amarante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Amarante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/\"},\"author\":{\"name\":\"Gabriel Amarante\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"headline\":\"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as\",\"datePublished\":\"2021-12-28T00:45:06+00:00\",\"dateModified\":\"2022-11-10T18:08:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/\"},\"wordCount\":552,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_importacao_de_autopecas_06_08_2019.jpg\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/\",\"name\":\"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_importacao_de_autopecas_06_08_2019.jpg\",\"datePublished\":\"2021-12-28T00:45:06+00:00\",\"dateModified\":\"2022-11-10T18:08:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_importacao_de_autopecas_06_08_2019.jpg\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_importacao_de_autopecas_06_08_2019.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/conheca-as-dicas-e-vantagem-de-importar-autopecas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\",\"name\":\"Gabriel Amarante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"caption\":\"Gabriel Amarante\"},\"sameAs\":[\"https:\\\/\\\/gabrielfreelancer.com.br\"],\"url\":\"https:\\\/\\\/mastersul.com.br\\\/es\\\/author\\\/amarante\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/es\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/","og_locale":"es_ES","og_type":"article","og_title":"[:pt]Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as[:] - Mastersul","og_description":"Voc\u00ea que trabalha com a comercializa\u00e7\u00e3o de autope\u00e7as j\u00e1 parou para pensar que vivemos no pa\u00eds que possui a quarta maior rede de estradas e rodovias do mundo? S\u00e3o mais de 1,8 milh\u00f5es de quil\u00f4metros de extens\u00e3o. De acordo com o IBGE, 61% do transporte de carga brasileira circula pelo asfalto. Mais da metade das [&hellip;]","og_url":"https:\/\/mastersul.com.br\/es\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/","og_site_name":"Mastersul","article_published_time":"2021-12-28T00:45:06+00:00","article_modified_time":"2022-11-10T18:08:33+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_importacao_de_autopecas_06_08_2019.jpg","type":"image\/jpeg"}],"author":"Gabriel Amarante","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Amarante","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/"},"author":{"name":"Gabriel Amarante","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"headline":"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as","datePublished":"2021-12-28T00:45:06+00:00","dateModified":"2022-11-10T18:08:33+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/"},"wordCount":552,"commentCount":0,"image":{"@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_importacao_de_autopecas_06_08_2019.jpg","articleSection":["Sem categoria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/","url":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/","name":"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_importacao_de_autopecas_06_08_2019.jpg","datePublished":"2021-12-28T00:45:06+00:00","dateModified":"2022-11-10T18:08:33+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"breadcrumb":{"@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_importacao_de_autopecas_06_08_2019.jpg","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_importacao_de_autopecas_06_08_2019.jpg","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/conheca-as-dicas-e-vantagem-de-importar-autopecas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a as dicas e vantagem de importar autope\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83","name":"Gabriel Amarante","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","caption":"Gabriel Amarante"},"sameAs":["https:\/\/gabrielfreelancer.com.br"],"url":"https:\/\/mastersul.com.br\/es\/author\/amarante\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/1881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/comments?post=1881"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/1881\/revisions"}],"predecessor-version":[{"id":2321,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/1881\/revisions\/2321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media\/1882"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media?parent=1881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/categories?post=1881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/tags?post=1881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}