{"id":2088,"date":"2021-12-28T21:52:14","date_gmt":"2021-12-29T00:52:14","guid":{"rendered":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/"},"modified":"2022-11-09T12:02:45","modified_gmt":"2022-11-09T15:02:45","slug":"noticia-do-comercio-exterior-importacao-de-trigo","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/es\/noticia-do-comercio-exterior-importacao-de-trigo\/","title":{"rendered":"Not\u00edcia do Com\u00e9rcio Exterior &#8211; Importa\u00e7\u00e3o de Trigo"},"content":{"rendered":"\r\n<h3 class=\"wp-block-heading\">NOT\u00cdCIAS SISCOMEX<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>Importa\u00e7\u00e3o n\u00b0 001\/2021<\/strong><br \/>Importa\u00e7\u00e3o de Trigo ao amparo da Resolu\u00e7\u00e3o GECEX n\u00ba 135\/2020<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>Exporta\u00e7\u00e3o n\u00b0 002\/2021<\/strong><br \/>Revoga\u00e7\u00e3o da Not\u00edcia SISCOMEX Exporta\u00e7\u00e3o n\u00b0 001\/2021<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>Exporta\u00e7\u00e3o n\u00b0 001\/2021<\/strong><br \/>Exclus\u00e3o do Reino Unido de LPCO de Cotas de Exporta\u00e7\u00e3o UE<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">PUBLICADO DOU 08\/01\/2021<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>CIRCULAR N\u00ba 1, DE 7 DE JANEIRO DE 2021<br \/>SECEX\/SECINT\/ME | 08\/01\/2021<\/strong><br \/>Prorroga por at\u00e9 dois meses, a partir de 22\/06\/2021, o prazo para conclus\u00e3o da revis\u00e3o de medida antidumping aplicada \u00e0s importa\u00e7\u00f5es brasileiras de seringas descart\u00e1veis de uso geral, comumente classificadas no subitens NCM 9018.31.11 e 9018.31.19, origin\u00e1rias da China, iniciada por interm\u00e9dio da Circular Secex n\u00ba 39\/2020. Torna p\u00fablicos os prazos que servir\u00e3o de par\u00e2metro para o restante da referida revis\u00e3o. Inicia avalia\u00e7\u00e3o de interesse p\u00fablico em rela\u00e7\u00e3o \u00e0s medidas antidumping aplicadas sobre as importa\u00e7\u00f5es brasileiras de seringas descart\u00e1veis de uso geral, comumente classificadas no subitens NCM 9018.31.11 e 9018.31.19, origin\u00e1rias da China.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>CIRCULAR N\u00ba 2, DE 7 DE JANEIRO DE 2021<br \/>SECEX\/SECINT\/ME | 08\/01\/2021<\/strong><br \/>Torna p\u00fablicos os novos prazos que servir\u00e3o de par\u00e2metro para o restante da revis\u00e3o da medida antidumping aplicada \u00e0s chapas pr\u00e9-sensibilizadas de alum\u00ednio para impress\u00e3o off-set, comumente classificadas nos itens NCM 3701.30.21 e 3701.30.31, origin\u00e1rias da China, de Taip\u00e9 Chin\u00eas, dos Estados Unidos da Am\u00e9rica e da Uni\u00e3o Europeia (incluindo o Reino Unido).<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">PUBLICADO DOU 07\/01\/2021<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>INSTRU\u00c7\u00c3O NORMATIVA N\u00ba 115, DE 18 DE DEZEMBRO DE 2020<br \/>SDA\/MAPA | 07\/01\/2021<\/strong><br \/>Retifica\u00e7\u00e3o da IN n\u00ba 115\/2020, que estabelece os requisitos fitossanit\u00e1rios para a importa\u00e7\u00e3o de sementes de cebolinha (Allium fistulosum) (Categoria 4, Classe 3), produzidas no Chile.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>MEDIDA PROVIS\u00d3RIA N\u00ba 1.026, DE 6 DE JANEIRO DE 2021<br \/>06\/01\/2021<\/strong><br \/>Disp\u00f5e sobre as medidas excepcionais relativas \u00e0 aquisi\u00e7\u00e3o de vacinas, insumos, bens e servi\u00e7os de log\u00edstica, tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00e3o, comunica\u00e7\u00e3o social e publicit\u00e1ria e treinamentos destinados \u00e0 vacina\u00e7\u00e3o contra a Covid-19 e sobre o Plano Nacional de Operacionaliza\u00e7\u00e3o da Vacina\u00e7\u00e3o contra a Covid-19. Disp\u00f5e ainda que a Anvisa, de acordo com suas normas, poder\u00e1 conceder autoriza\u00e7\u00e3o excepcional e tempor\u00e1ria para a importa\u00e7\u00e3o e distribui\u00e7\u00e3o de quaisquer vacinas contra a Covid-19, materiais, medicamentos, equipamentos e insumos da \u00e1rea de sa\u00fade sujeitos \u00e0 vigil\u00e2ncia sanit\u00e1ria, sem registro na Anvisa e considerados essenciais para auxiliar no combate \u00e0 Covid-19, desde que registrados por, no m\u00ednimo, uma das autoridades sanit\u00e1rias estrangeiras que menciona, e autorizados \u00e0 distribui\u00e7\u00e3o em seus respectivos pa\u00edses. Esta MP se aplica aos atos praticados e aos contratos ou instrumentos cong\u00eaneres firmados at\u00e9 31\/07\/2021, independentemente do seu prazo de execu\u00e7\u00e3o ou de suas prorroga\u00e7\u00f5es.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 143, DE 6 DE JANEIRO DE 2021<br \/>GECEX\/CAMEX\/ME | 07\/01\/2021<\/strong><br \/>Concede redu\u00e7\u00e3o tempor\u00e1ria da al\u00edquota do Imposto de Importa\u00e7\u00e3o ao amparo da Resolu\u00e7\u00e3o GMC n\u00ba 49\/2019 em rela\u00e7\u00e3o aos itens NCM 3907.40.90 e 8452.10.00. Esta Resolu\u00e7\u00e3o entrar\u00e1 em vigor sete dias ap\u00f3s a data de sua publica\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 144, DE 6 DE JANEIRO DE 2021<br \/>GECEX\/CAMEX\/ME | 07\/01\/2021<\/strong><br \/>Inclui os itens NCM 9018.31.11, 9018.31.19, 9018.31.90, 9018.32.19 e 9018.39.10 na Resolu\u00e7\u00e3o n\u00ba 17\/2020, que concede redu\u00e7\u00e3o tempor\u00e1ria para zero por cento da al\u00edquota ad valorem do Imposto de Importa\u00e7\u00e3o das mercadorias classificadas nos c\u00f3digos NCM que especifica ao amparo do art. 50, al\u00ednea \u00abd\u00bb, do Tratado de Montevid\u00e9u de 1980, internalizado pelo Decreto Legislativo n\u00ba 66\/1981. Esta Resolu\u00e7\u00e3o entrar\u00e1 em vigor no dia seguinte \u00e0 data de sua publica\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 145, DE 6 DE JANEIRO DE 2021<br \/>GECEX\/CAMEX\/ME | 07\/01\/2021<\/strong><br \/>Suspende a aplica\u00e7\u00e3o, por raz\u00f5es de interesse p\u00fablico, at\u00e9 30\/06\/2021, do direito antidumping \u00e0s importa\u00e7\u00f5es brasileiras de seringas descart\u00e1veis de uso geral, de pl\u00e1stico, com capacidade de 1 ml, 3 ml, 5 ml, 10 ml ou 20 ml, com ou sem agulhas, comumente classificadas nos itens NCM 9018.31.11 e 9018.31.19, origin\u00e1rias da China.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">PUBLICADO DOU 06\/01\/2021<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 142, DE 31 DE DEZEMBRO DE 2020<br \/>GECEX\/CAMEX\/ME | 06\/01\/2021<\/strong><br \/>Reaplica o direito antidumping definitivo, que havia sido aplicado por um prazo de at\u00e9 cinco anos e suspenso, \u00e0s importa\u00e7\u00f5es brasileiras de cadeados, comumente classificados no subitem NCM 8301.10.00, origin\u00e1rias da China, a ser recolhido sob a forma de al\u00edquota espec\u00edfica fixada em d\u00f3lares estadunidenses por quilograma a ser aplicada sobre o valor aduaneiro da mercadoria, nos montantes especificados.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">PUBLICADO DOU 05\/01\/2021<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>INSTRU\u00c7\u00c3O NORMATIVA MAPA N\u00ba 71, DE 29 DE DEZEMBRO DE 2020<br \/>GM\/MAPA | 05\/01\/2021<\/strong><br \/>Altera a IN n\u00ba 25\/2020, que estabelece que a autoriza\u00e7\u00e3o de importa\u00e7\u00e3o de esp\u00e9cies vegetais, suas partes, produtos e subprodutos, e outros artigos regulamentados fica condicionada \u00e0 defini\u00e7\u00e3o dos requisitos fitossanit\u00e1rios espec\u00edficos estabelecidos por meio de An\u00e1lise de Risco de Pragas (ARP), de acordo com a Conven\u00e7\u00e3o Internacional para a Prote\u00e7\u00e3o dos Vegetais. Esta IN entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>SOLU\u00c7\u00c3O DE CONSULTA N\u00ba 165, DE 28 DE DEZEMBRO DE 2020<br \/>COSIT\/SUTRI\/SUBGRFB\/RFB\/ME | 05\/01\/2021<\/strong><br \/>Disp\u00f5e que, desde que observados os requisitos contidos na legisla\u00e7\u00e3o relativa \u00e0 certifica\u00e7\u00e3o digital, em especial, na MP n\u00ba 2.200-2\/2001, que permitam garantir a autenticidade, a integridade e a validade jur\u00eddica do documento, \u00e9 poss\u00edvel a emiss\u00e3o de fatura comercial em formato nato-digital pelo representante do exportador residente no pa\u00eds (legalmente constitu\u00eddo e habilitado pelo exportador). A emiss\u00e3o da fatura comercial tal como descrito n\u00e3o dispensa o importador de, em momento posterior, quando do registro da DI, observar e cumprir as disposi\u00e7\u00f5es da IN RFB n\u00ba 680\/2006, norma cogente, em especial o seu art. 19.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">PUBLICADO DOU 04\/01\/2021<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>CIRCULAR N\u00ba 86, DE 31 DE DEZEMBRO DE 2020<br \/>SECEX\/SECINT\/ME | 04\/01\/2021<\/strong><br \/>Torna p\u00fablicos os novos prazos que servir\u00e3o de par\u00e2metro para o restante da revis\u00e3o de final de per\u00edodo das medidas antidumping aplicadas \u00e0s importa\u00e7\u00f5es brasileiras de tubos de pl\u00e1stico para coleta de sangue a v\u00e1cuo, comumente classificadas nos subitens NCM 3822.00.90, 3926.90.40 e 9018.39.99, origin\u00e1rias da Alemanha, da China, dos Estados Unidos da Am\u00e9rica e do Reino Unido da Gr\u00e3-Bretanha e Irlanda do Norte, iniciada por interm\u00e9dio da Circular Secex n\u00ba 30\/2020.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>INSTRU\u00c7\u00c3O NORMATIVA RFB N\u00ba 2.002, DE 29 DE DEZEMBRO DE 2020<br \/>RFB\/ME | 31\/12\/2020<\/strong><br \/>Altera a IN n\u00ba 680\/2006, que disciplina o despacho aduaneiro de importa\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA ALF\/GRU N\u00ba 181, DE 28 DE DEZEMBRO DE 2020<br \/>ALF-Aer.SP-GRU\/SRRF8\u00aa\/RFB\/MR | 04\/01\/2021<\/strong><br \/>Reconhece \u00e1reas administrativas da Receita Federal do Brasil no Aeroporto Internacional de S\u00e3o Paulo\/Governador Franco Montoro.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA ALF\/GRU N\u00ba 182, DE 28 DE DEZEMBRO DE 2020<br \/>ALF-Aer.SP-GRU\/SRRF8\u00aa\/RFB\/MR | 04\/01\/2021<\/strong><br \/>Altera a Portaria n\u00ba 87\/2016, que autoriza, em car\u00e1ter prec\u00e1rio, a entrada de cargas, unitizadas ou n\u00e3o, de remessa expressa ou postal em exporta\u00e7\u00e3o, oriundas respectivamente do Terminal de Carga Expressa (Tecex) ou do Terminal de Carga A\u00e9rea Internacional (GTCAI) da ECT, no Terminal de Carga A\u00e9rea (Teca) de Exporta\u00e7\u00e3o, para serem submetidas \u00e0 inspe\u00e7\u00e3o de seguran\u00e7a da avia\u00e7\u00e3o e, se for o caso, \u00e0 unitiza\u00e7\u00e3o final para embarque ao exterior.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA DRF\/NIU N\u00ba 86, DE 29 DE DEZEMBRO DE 2020<br \/>DRF-NOVA IGUA\u00c7U\/SRRF7\u00aa\/RFB\/MR | 04\/01\/2021<\/strong><br \/>Disciplina os procedimentos relacionados \u00e0 verifica\u00e7\u00e3o f\u00edsica remota de mercadorias, por meio de imagens, na importa\u00e7\u00e3o ou exporta\u00e7\u00e3o, no \u00e2mbito da DRF\/NIU.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA INTERMINISTERIAL ME\/MCTI N\u00ba 434, DE 31 DE DEZEMBRO 2020<br \/>GM\/ME | 31\/12\/2020<\/strong><br \/>Disp\u00f5e sobre os bens e insumos que far\u00e3o jus \u00e0s redu\u00e7\u00f5es de al\u00edquotas de que trata o art. 3\u00ba da Lei n\u00ba 11.484\/2007 (Aplica\u00e7\u00e3o do Programa de Apoio ao Desenvolvimento Tecnol\u00f3gico da Ind\u00fastria de Semicondutores &#8211; PADIS).<br \/><br \/><strong>PORTARIA INTERMINISTERIAL N\u00ba 76, DE 28 DE DEZEMBRO DE 2020<br \/>SEPEC\/ME | 04\/01\/2021<\/strong><br \/>Estabelece o PPB para o produto m\u00e1quina autom\u00e1tica de processamento de dados, com unidade central de processamento, monitor de v\u00eddeo e unidade de entrada, contida em m\u00f3vel pr\u00f3prio, tipo mesa interativa, industrializado no Pa\u00eds.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA INTERMINISTERIAL N\u00ba 77, DE 28 DE DEZEMBRO DE 2020<br \/>SEPEC\/ME | 04\/01\/2021<\/strong><br \/>Estabelece o PPB para o produto m\u00e1quina autom\u00e1tica de processamento de dados, com unidade central de processamento, monitor de v\u00eddeo e unidade de entrada, contida em m\u00f3vel pr\u00f3prio, tipo mesa interativa, industrializado na Zona Franca de Manaus.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA INTERMINISTERIAL N\u00ba 78, DE 28 DE DEZEMBRO DE 2020<br \/>SEPEC\/ME | 04\/01\/2021<\/strong><br \/>Altera a Portaria Interministerial MDIC\/MCTI n\u00ba 186\/2015, que estabelece o PPB para televisor com tela de cristal l\u00edquido, industrializado na Zona Franca de Manaus.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA ME N\u00ba 425, DE 29 DE DEZEMBRO DE 2020<br \/>GM\/ME | 31\/12\/2020<\/strong><br \/>Fixa o valor do limite global anual, para o exerc\u00edcio de 2021, das importa\u00e7\u00f5es destinadas \u00e0 pesquisa cient\u00edfica e tecnol\u00f3gica, nos termos da Lei n\u00ba 8.010\/1990 e da Lei n\u00ba 8.032\/1990.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 392, DE 22 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova o Regulamento T\u00e9cnico da Qualidade e os Requisitos de Avalia\u00e7\u00e3o da Conformidade para Isqueiros a G\u00e1s &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 393, DE 22 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova o Regulamento T\u00e9cnico da Qualidade e os Requisitos de Avalia\u00e7\u00e3o da Conformidade para Pneus de Bicicletas de Uso Adulto &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 394, DE 23 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova os Requisitos de Avalia\u00e7\u00e3o da Conformidade para Copos Pl\u00e1sticos Descart\u00e1veis &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 395, DE 28 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova o Regulamento T\u00e9cnico da Qualidade e os Requisitos de Avalia\u00e7\u00e3o da Conformidade para Empresa Inspetora de Contentores Intermedi\u00e1rios para Gran\u00e9is (IBC) Destinados ao Transporte Terrestre de Produtos Perigosos &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 396, DE 28 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova os Requisitos de Avalia\u00e7\u00e3o da Conformidade para Coletes de Seguran\u00e7a de Alta Visibilidade &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 400, DE 28 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova o Regulamento T\u00e9cnico da Qualidade e os Requisitos de Avalia\u00e7\u00e3o da Conformidade para Fornecedor de Quebra-Mato &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<br \/><br \/><strong>PORTARIA N\u00ba 401, DE 28 DE DEZEMBRO DE 2020<br \/>INMETRO\/ME | 31\/12\/2020<\/strong><br \/>Aprova os Requisitos de Avalia\u00e7\u00e3o da Conformidade para M\u00f3veis Escolares &#8211; Cadeiras e Mesas para Conjunto Aluno Individual &#8211; Consolidado. Revoga os normativos que menciona. Esta Portaria entra em vigor em 01\/02\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 50, DE 30 DE DEZEMBRO DE 2020<br \/>ALF-PORTO DE ITAJA\u00cd\/SRRF9\u00aa\/RFB\/ME | 04\/01\/2021<\/strong><br \/>Disciplina as opera\u00e7\u00f5es de fornecimento de bordo, retirada de res\u00edduos, embarque e desembarque de tripulantes procedentes do exterior ou a ele destinados, retirada e devolu\u00e7\u00e3o de pe\u00e7as para conserto, manuten\u00e7\u00e3o ou reparo, e demais servi\u00e7os prestados \u00e0s embarca\u00e7\u00f5es atracadas em recintos alfandegados jurisdicionadas pela Alf\u00e2ndega da Receita Federal do Brasil do Porto de Itagua\u00ed ou fundeados nas Ba\u00edas de Sepetiba e Ilha Grande, bem como o transporte de mercadorias, equipamentos e tripulantes entre o cais do porto e os navios fundeados na ba\u00eda de Sepetiba ou da Ilha Grande. Esta Portaria entra em vigor na data de sua publica\u00e7\u00e3o, com prazo de 20 dias da publica\u00e7\u00e3o para adapta\u00e7\u00e3o de procedimentos, e revoga inteiramente a Portaria ALF\/IGI n\u00ba 56\/2018, e demais dispositivos em contr\u00e1rio.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 73, DE 31 DE DEZEMBRO DE 2020<br \/>SECEX\/SECINT\/ME | 04\/01\/2021<\/strong><br \/>Estabelece crit\u00e9rios para aloca\u00e7\u00e3o de cota para importa\u00e7\u00e3o, em rela\u00e7\u00e3o ao item NCM 1107.10.10, determinada pela Resolu\u00e7\u00e3o Gecex\/Camex n\u00ba 129\/2020. Esta Portaria fica revogada com o fim da vig\u00eancia da cota regulamentada pelo art. 1\u00ba.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 74, DE 31 DE DEZEMBRO DE 2020<br \/>SECEX\/SECINT\/ME | 04\/01\/2021<\/strong><br \/>Estabelece crit\u00e9rios para aloca\u00e7\u00e3o de cotas para importa\u00e7\u00e3o, em rela\u00e7\u00e3o aos itens NCM 0303.53.00, 3206.11.10, 4805.92.90 e 7601.10.00, determinadas pela Resolu\u00e7\u00e3o Gecex\/Camex n\u00ba 129\/2020. Revoga o item 2.5 da al\u00ednea \u00abb\u00bb do inciso CXXIX do art. 1\u00ba do Anexo III da Portaria Secex n\u00ba 23\/2011. Esta Portaria fica revogada com o fim da vig\u00eancia das cotas regulamentadas pelo art. 1\u00ba. Esta Portaria entra em vigor no dia 01\/01\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>PORTARIA N\u00ba 75, DE 31 DE DEZEMBRO DE 2020<br \/>SECEX\/SECINT\/ME | 04\/01\/2021<\/strong><br \/>Estabelece crit\u00e9rios para aloca\u00e7\u00e3o de cota para importa\u00e7\u00e3o, em rela\u00e7\u00e3o aos itens NCM 1001.19.00 e 1001.99.00, determinada pela Resolu\u00e7\u00e3o Gecex\/Camex n\u00ba 135\/2020. Esta Portaria entra em vigor em 01\/01\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 138, DE 31 DE DEZEMBRO DE 2020<br \/>GECEX\/CAMEX\/ME | 04\/01\/2021<\/strong><br \/>Altera a Lista de Autope\u00e7as N\u00e3o Produzidas, constantes dos Anexos I e II da Resolu\u00e7\u00e3o Camex n\u00ba 23\/2019. Esta Resolu\u00e7\u00e3o entrar\u00e1 em vigor a partir de 11\/01\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 139, DE 31 DE DEZEMBRO DE 2020<br \/>GECEX\/CAMEX\/ME | 04\/01\/2021<\/strong><br \/>Altera as Listas de Autope\u00e7as n\u00e3o Produzidas, constantes dos Anexos I e II da Resolu\u00e7\u00e3o Camex n\u00ba 102\/2018. Esta Resolu\u00e7\u00e3o entrar\u00e1 em vigor a partir de 11\/01\/2021.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>RESOLU\u00c7\u00c3O GECEX N\u00ba 140, DE 31 DE DEZEMBRO DE 2020<br \/>GECEX\/CAMEX\/ME | 04\/01\/2021<\/strong><br \/>Encerra a avalia\u00e7\u00e3o de escopo e determina que as importa\u00e7\u00f5es de batatas pr\u00e9-fritas congeladas, sem cobertura, borrifadas com especiarias, comumente classificadas no item NCM 2004.10.00, n\u00e3o est\u00e3o sujeitas \u00e0 aplica\u00e7\u00e3o das medidas antidumping sobre as importa\u00e7\u00f5es de batatas congeladas da Alemanha, B\u00e9lgica, Fran\u00e7a e Pa\u00edses Baixos, institu\u00eddas pela Resolu\u00e7\u00e3o Camex n\u00ba 6\/2017.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>SOLU\u00c7\u00c3O DE CONSULTA N\u00ba 152, DE 21 DE DEZEMBRO DE 2020<br \/>COSIT\/SUTRI\/SUBGRFB\/RFB\/ME | 31\/12\/2020<\/strong><br \/>Disp\u00f5e que o despacho aduaneiro de bens cuja importa\u00e7\u00e3o n\u00e3o esteja atrelada \u00e0 compra e venda internacional n\u00e3o necessita ser instru\u00eddo com fatura comercial, a teor do art. 18, \u00a7 2\u00ba, inciso II, al\u00ednea \u00aba\u00bb , da IN SRF n\u00ba 680\/2006. A inexist\u00eancia de transfer\u00eancia da propriedade dos bens importados, configurada pela manuten\u00e7\u00e3o de sua titularidade ap\u00f3s a nacionaliza\u00e7\u00e3o, impede a aplica\u00e7\u00e3o das sistem\u00e1ticas de importa\u00e7\u00e3o por conta e ordem de terceiro e importa\u00e7\u00e3o por encomenda, as quais pressup\u00f5em, respectivamente, as figuras do adquirente e do encomendante.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><strong>SOLU\u00c7\u00c3O DE CONSULTA N\u00ba 174, DE 28 DE AGOSTO DE 2020<br \/>COSIT\/SUTRI\/RFB\/ME | 04\/01\/2021<\/strong><br \/>Disp\u00f5e que a importa\u00e7\u00e3o de armas de fogo para venda no varejo n\u00e3o \u00e9 impedimento ao recolhimento dos tributos pelo regime do Simples Nacional. Deve a receita da venda no varejo das referidas armas de fogo ser tributada conforme o Anexo II da LC n\u00ba 123\/2006.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">LEGISLA\u00c7\u00c3O TRIBUT\u00c1RIA \u2013 ESTADO DO PARAN\u00c1<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\"><a href=\"https:\/\/www.arinternet.pr.gov.br\/portalsefa\/_l_downloadlegislacao2.asp?eTpDoc=0&#038;eTpPer=5&#038;eTpMod=1\"><strong>Clique aqui<\/strong><\/a>\u00a0e confira na integra os documentos cadastrados nos \u00faltimos 30 dias.<\/p>\r\n\r\n\r\n<hr class=\"wp-block-separator\" \/>\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"font-size: 19px;\">Atualize-se diariamente com as principais not\u00edcias e legisla\u00e7\u00f5es do Com\u00e9rcio Exterior. Acompanhe nossas redes:<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size: 19px;\"><strong><a href=\"http:\/\/www.linkedin.com\/company\/mastersul-comex\">Linkedin<\/a>\u00a0|\u00a0<a href=\"http:\/\/www.facebook.com\/mastersul\">Facebook<\/a>\u00a0|\u00a0<a href=\"https:\/\/www.instagram.com\/mastersul_comex\/?hl=pt-br\">Instagram<\/a><\/strong><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>NOT\u00cdCIAS SISCOMEX Importa\u00e7\u00e3o n\u00b0 001\/2021Importa\u00e7\u00e3o de Trigo ao amparo da Resolu\u00e7\u00e3o GECEX n\u00ba 135\/2020 Exporta\u00e7\u00e3o n\u00b0 002\/2021Revoga\u00e7\u00e3o da Not\u00edcia SISCOMEX Exporta\u00e7\u00e3o n\u00b0 001\/2021 Exporta\u00e7\u00e3o n\u00b0 001\/2021Exclus\u00e3o do Reino Unido de LPCO de Cotas de Exporta\u00e7\u00e3o UE &nbsp; PUBLICADO DOU 08\/01\/2021 CIRCULAR N\u00ba 1, DE 7 DE JANEIRO DE 2021SECEX\/SECINT\/ME | 08\/01\/2021Prorroga por at\u00e9 dois meses, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2080,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Not\u00edcia do Com\u00e9rcio Exterior - Importa\u00e7\u00e3o de Trigo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/es\/noticia-do-comercio-exterior-importacao-de-trigo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Not\u00edcia do Com\u00e9rcio Exterior - Importa\u00e7\u00e3o de Trigo\" \/>\n<meta property=\"og:description\" content=\"NOT\u00cdCIAS SISCOMEX Importa\u00e7\u00e3o n\u00b0 001\/2021Importa\u00e7\u00e3o de Trigo ao amparo da Resolu\u00e7\u00e3o GECEX n\u00ba 135\/2020 Exporta\u00e7\u00e3o n\u00b0 002\/2021Revoga\u00e7\u00e3o da Not\u00edcia SISCOMEX Exporta\u00e7\u00e3o n\u00b0 001\/2021 Exporta\u00e7\u00e3o n\u00b0 001\/2021Exclus\u00e3o do Reino Unido de LPCO de Cotas de Exporta\u00e7\u00e3o UE &nbsp; PUBLICADO DOU 08\/01\/2021 CIRCULAR N\u00ba 1, DE 7 DE JANEIRO DE 2021SECEX\/SECINT\/ME | 08\/01\/2021Prorroga por at\u00e9 dois meses, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/es\/noticia-do-comercio-exterior-importacao-de-trigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-29T00:52:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T15:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gabriel Amarante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Amarante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/\"},\"author\":{\"name\":\"Gabriel Amarante\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"headline\":\"Not\u00edcia do Com\u00e9rcio Exterior &#8211; Importa\u00e7\u00e3o de Trigo\",\"datePublished\":\"2021-12-29T00:52:14+00:00\",\"dateModified\":\"2022-11-09T15:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/\"},\"wordCount\":2393,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png\",\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/\",\"name\":\"Not\u00edcia do Com\u00e9rcio Exterior - Importa\u00e7\u00e3o de Trigo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png\",\"datePublished\":\"2021-12-29T00:52:14+00:00\",\"dateModified\":\"2022-11-09T15:02:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/noticia-do-comercio-exterior-importacao-de-trigo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcia do Com\u00e9rcio Exterior &#8211; Importa\u00e7\u00e3o de Trigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/462270e149759539a07d47944ab9fa83\",\"name\":\"Gabriel Amarante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g\",\"caption\":\"Gabriel Amarante\"},\"sameAs\":[\"https:\\\/\\\/gabrielfreelancer.com.br\"],\"url\":\"https:\\\/\\\/mastersul.com.br\\\/es\\\/author\\\/amarante\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Not\u00edcia do Com\u00e9rcio Exterior - Importa\u00e7\u00e3o de Trigo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/es\/noticia-do-comercio-exterior-importacao-de-trigo\/","og_locale":"es_ES","og_type":"article","og_title":"[:pt]Not\u00edcia do Com\u00e9rcio Exterior - Importa\u00e7\u00e3o de Trigo[:] - Mastersul","og_description":"NOT\u00cdCIAS SISCOMEX Importa\u00e7\u00e3o n\u00b0 001\/2021Importa\u00e7\u00e3o de Trigo ao amparo da Resolu\u00e7\u00e3o GECEX n\u00ba 135\/2020 Exporta\u00e7\u00e3o n\u00b0 002\/2021Revoga\u00e7\u00e3o da Not\u00edcia SISCOMEX Exporta\u00e7\u00e3o n\u00b0 001\/2021 Exporta\u00e7\u00e3o n\u00b0 001\/2021Exclus\u00e3o do Reino Unido de LPCO de Cotas de Exporta\u00e7\u00e3o UE &nbsp; PUBLICADO DOU 08\/01\/2021 CIRCULAR N\u00ba 1, DE 7 DE JANEIRO DE 2021SECEX\/SECINT\/ME | 08\/01\/2021Prorroga por at\u00e9 dois meses, [&hellip;]","og_url":"https:\/\/mastersul.com.br\/es\/noticia-do-comercio-exterior-importacao-de-trigo\/","og_site_name":"Mastersul","article_published_time":"2021-12-29T00:52:14+00:00","article_modified_time":"2022-11-09T15:02:45+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png","type":"image\/png"}],"author":"Gabriel Amarante","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Amarante","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/"},"author":{"name":"Gabriel Amarante","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"headline":"Not\u00edcia do Com\u00e9rcio Exterior &#8211; Importa\u00e7\u00e3o de Trigo","datePublished":"2021-12-29T00:52:14+00:00","dateModified":"2022-11-09T15:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/"},"wordCount":2393,"commentCount":0,"image":{"@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png","articleSection":["Sem categoria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/","url":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/","name":"Not\u00edcia do Com\u00e9rcio Exterior - Importa\u00e7\u00e3o de Trigo","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png","datePublished":"2021-12-29T00:52:14+00:00","dateModified":"2022-11-09T15:02:45+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83"},"breadcrumb":{"@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2022\/11\/MS_RD_e_mail_noticias-do-comexa_capa_24_09_2018-2.png","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/noticia-do-comercio-exterior-importacao-de-trigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcia do Com\u00e9rcio Exterior &#8211; Importa\u00e7\u00e3o de Trigo"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/462270e149759539a07d47944ab9fa83","name":"Gabriel Amarante","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b353e3e410b34e6bf21da9daf0ca97fd281ee9482091f81c438d5225f0e1e19?s=96&d=mm&r=g","caption":"Gabriel Amarante"},"sameAs":["https:\/\/gabrielfreelancer.com.br"],"url":"https:\/\/mastersul.com.br\/es\/author\/amarante\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/2088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/comments?post=2088"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/2088\/revisions"}],"predecessor-version":[{"id":2186,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/2088\/revisions\/2186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media\/2080"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media?parent=2088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/categories?post=2088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/tags?post=2088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}