{"id":4714,"date":"2025-11-17T15:35:26","date_gmt":"2025-11-17T18:35:26","guid":{"rendered":"https:\/\/mastersul.com.br\/?p=4714"},"modified":"2025-11-17T15:35:26","modified_gmt":"2025-11-17T18:35:26","slug":"mix-de-noticias-17-11-2025-cop-30","status":"publish","type":"post","link":"https:\/\/mastersul.com.br\/es\/mix-de-noticias-17-11-2025-cop-30\/","title":{"rendered":"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos"},"content":{"rendered":"<h4><b>01 &#8211; COP 30 traz novas exig\u00eancias para exporta\u00e7\u00e3o de insumos amaz\u00f4nicos<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">A COP 30 deve inaugurar uma nova etapa para o com\u00e9rcio exterior de insumos originados da Amaz\u00f4nia. O encontro deve acelerar a constru\u00e7\u00e3o de crit\u00e9rios rigorosos de rastreabilidade e comprova\u00e7\u00e3o de origem, voltados especialmente \u00e0 bioeconomia. Na pr\u00e1tica, exportar esses produtos exigir\u00e1 documenta\u00e7\u00e3o mais robusta sobre toda a cadeia produtiva.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos, destacando empresas que conseguirem demonstrar sustentabilidade ambiental, responsabilidade social e regularidade fundi\u00e1ria. Essas exig\u00eancias tendem a se tornar fator decisivo para acesso a mercados mais exigentes, especialmente na Europa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora eleve o n\u00edvel de responsabilidade do setor, o movimento tamb\u00e9m abre espa\u00e7o para maior valoriza\u00e7\u00e3o dos produtos amaz\u00f4nicos. Mercados que buscam cadeias produtivas verdes podem aumentar a demanda por itens certificados, fortalecendo a economia regional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na agenda global contra mudan\u00e7as clim\u00e1ticas, a bioeconomia amaz\u00f4nica ganha centralidade, e as novas regras devem funcionar como um divisor de \u00e1guas para quem atua com exporta\u00e7\u00e3o desses insumos. Trata-se de uma mudan\u00e7a que prepara o Brasil para competir em um mercado mais sustent\u00e1vel e regulado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>02 &#8211; Exporta\u00e7\u00f5es do agroneg\u00f3cio batem recorde hist\u00f3rico em outubro<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">\u00a0agroneg\u00f3cio brasileiro registrou o maior valor de exporta\u00e7\u00f5es para um m\u00eas de outubro na s\u00e9rie hist\u00f3rica, somando US$ 15,49 bilh\u00f5es. O avan\u00e7o de 8,5% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano anterior foi impulsionado tanto pelos produtos tradicionais, como soja e carnes, quanto por itens que v\u00eam ganhando espa\u00e7o no mercado internacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Produtos como amendoim e ra\u00e7\u00f5es para animais de estima\u00e7\u00e3o registraram crescimentos expressivos, mostrando a diversifica\u00e7\u00e3o da pauta exportadora. A amplia\u00e7\u00e3o de mercados e a alta demanda externa contribu\u00edram para o desempenho acima do previsto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No acumulado do ano, de janeiro a outubro, o super\u00e1vit do agroneg\u00f3cio chegou a US$ 124,97 bilh\u00f5es. Trata-se de um dos maiores resultados j\u00e1 registrados, consolidando o setor como pilar da balan\u00e7a comercial brasileira.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O resultado refor\u00e7a a capacidade do Brasil de atender \u00e0 demanda global por alimentos, ao mesmo tempo em que evidencia a import\u00e2ncia de manter efici\u00eancia log\u00edstica e competitividade para continuar ampliando mercados.<\/span><\/p>\n<h4><\/h4>\n<h4><strong>03 &#8211; EUA reduzem tarifas para caf\u00e9, carne bovina e frutas<\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">O governo dos Estados Unidos anunciou a redu\u00e7\u00e3o de tarifas sobre mais de 200 produtos aliment\u00edcios, incluindo itens relevantes para o Brasil, como caf\u00e9, carne bovina e frutas tropicais. A medida faz parte de uma estrat\u00e9gia para conter a infla\u00e7\u00e3o interna e responder \u00e0 press\u00e3o dos consumidores diante da alta nos pre\u00e7os de alimentos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar do movimento, algumas tarifas adicionais permanecem ativas. Produtos brasileiros, mesmo com a redu\u00e7\u00e3o, ainda enfrentam cobran\u00e7a de cerca de 40%, segundo autoridades brasileiras. O governo considera a medida positiva, mas refor\u00e7a que o cen\u00e1rio ideal seria uma negocia\u00e7\u00e3o que abrangesse todos os encargos extras.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A diminui\u00e7\u00e3o das tarifas tende a facilitar a entrada dos produtos brasileiros no mercado norte-americano. Isso pode fortalecer setores j\u00e1 consolidados, como caf\u00e9 e prote\u00edna animal, al\u00e9m de abrir novas oportunidades para frutas e outros alimentos tropicais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O al\u00edvio tarif\u00e1rio deve incentivar a retomada de volumes mais competitivos e reequilibrar a presen\u00e7a do Brasil em um dos mercados mais relevantes do mundo, enquanto negocia\u00e7\u00f5es diplom\u00e1ticas continuam em busca de condi\u00e7\u00f5es ainda mais favor\u00e1veis.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 &#8211; COP 30 traz novas exig\u00eancias para exporta\u00e7\u00e3o de insumos amaz\u00f4nicos A COP 30 deve inaugurar uma nova etapa para o com\u00e9rcio exterior de insumos originados da Amaz\u00f4nia. O encontro deve acelerar a constru\u00e7\u00e3o de crit\u00e9rios rigorosos de rastreabilidade e comprova\u00e7\u00e3o de origem, voltados especialmente \u00e0 bioeconomia. Na pr\u00e1tica, exportar esses produtos exigir\u00e1 documenta\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[8],"tags":[],"class_list":["post-4714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos<\/title>\n<meta name=\"description\" content=\"A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/es\/mix-de-noticias-17-11-2025-cop-30\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos\" \/>\n<meta property=\"og:description\" content=\"A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/es\/mix-de-noticias-17-11-2025-cop-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T18:35:26+00:00\" \/>\n<meta name=\"author\" content=\"Equipe Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/\"},\"author\":{\"name\":\"Equipe Marketing\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"headline\":\"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos\",\"datePublished\":\"2025-11-17T18:35:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/\"},\"wordCount\":607,\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg\",\"articleSection\":[\"Informa\u00e7\u00e3o\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/\",\"name\":\"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg\",\"datePublished\":\"2025-11-17T18:35:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\"},\"description\":\"A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mastersul.com.br\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg\",\"width\":2560,\"height\":1422},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/mix-de-noticias-17-11-2025-cop-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#\\\/schema\\\/person\\\/f5438feb255e55fba8064f56e8107665\",\"name\":\"Equipe Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g\",\"caption\":\"Equipe Marketing\"},\"url\":\"https:\\\/\\\/mastersul.com.br\\\/es\\\/author\\\/mastersul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos","description":"A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/es\/mix-de-noticias-17-11-2025-cop-30\/","og_locale":"es_ES","og_type":"article","og_title":"[:pt]COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos[:] - Mastersul","og_description":"[:pt]A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos[:]","og_url":"https:\/\/mastersul.com.br\/es\/mix-de-noticias-17-11-2025-cop-30\/","og_site_name":"Mastersul","article_published_time":"2025-11-17T18:35:26+00:00","author":"Equipe Marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Marketing","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#article","isPartOf":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/"},"author":{"name":"Equipe Marketing","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"headline":"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos","datePublished":"2025-11-17T18:35:26+00:00","mainEntityOfPage":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/"},"wordCount":607,"image":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/11\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg","articleSection":["Informa\u00e7\u00e3o"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/","url":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/","name":"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#primaryimage"},"image":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#primaryimage"},"thumbnailUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/11\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg","datePublished":"2025-11-17T18:35:26+00:00","author":{"@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665"},"description":"A expectativa \u00e9 que novos padr\u00f5es internacionais criem um \u201cselo\u201d de confiabilidade para insumos amaz\u00f4nicos","breadcrumb":{"@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#primaryimage","url":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/11\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg","contentUrl":"https:\/\/mastersul.com.br\/wp-content\/uploads\/2025\/11\/cop30-em-belem-brasil-conferencia-sobre-mudancas-climaticas-scaled.jpg","width":2560,"height":1422},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/mix-de-noticias-17-11-2025-cop-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"COP 30 deve redefinir regras do com\u00e9rcio exterior para insumos amaz\u00f4nicos"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/mastersul.com.br\/#\/schema\/person\/f5438feb255e55fba8064f56e8107665","name":"Equipe Marketing","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff1f02ddf747b5ed3945c0dacdde3765fe3f60c0c5cc404e8aff6dcc51b5c05b?s=96&d=mm&r=g","caption":"Equipe Marketing"},"url":"https:\/\/mastersul.com.br\/es\/author\/mastersul\/"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/4714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/comments?post=4714"}],"version-history":[{"count":1,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/4714\/revisions"}],"predecessor-version":[{"id":4720,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/posts\/4714\/revisions\/4720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media\/4718"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media?parent=4714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/categories?post=4714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/tags?post=4714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}