{"id":233,"date":"2022-07-18T00:05:31","date_gmt":"2022-07-18T03:05:31","guid":{"rendered":"https:\/\/mastersul.com.br\/?post_type=servico&#038;p=233"},"modified":"2022-10-13T10:20:59","modified_gmt":"2022-10-13T13:20:59","slug":"logistica-internacional","status":"publish","type":"servico","link":"https:\/\/mastersul.com.br\/es\/servico\/logistica-internacional\/","title":{"rendered":"Log\u00edstica Internacional"},"parent":0,"template":"","class_list":["post-233","servico","type-servico","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Log\u00edstica Internacional - Mastersul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mastersul.com.br\/es\/servico\/logistica-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"pt_BR\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Log\u00edstica Internacional - Mastersul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mastersul.com.br\/es\/servico\/logistica-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Mastersul\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-13T13:20:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/servico\\\/logistica-internacional\\\/\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/servico\\\/logistica-internacional\\\/\",\"name\":\"Log\u00edstica Internacional - Mastersul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\"},\"datePublished\":\"2022-07-18T03:05:31+00:00\",\"dateModified\":\"2022-10-13T13:20:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/servico\\\/logistica-internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mastersul.com.br\\\/servico\\\/logistica-internacional\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/servico\\\/logistica-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servi\u00e7os\",\"item\":\"https:\\\/\\\/mastersul.com.br\\\/servico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Log\u00edstica Internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mastersul.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mastersul.com.br\\\/\",\"name\":\"Mastersul\",\"description\":\"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mastersul.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Log\u00edstica Internacional - Mastersul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mastersul.com.br\/es\/servico\/logistica-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Log\u00edstica Internacional - Mastersul","og_url":"https:\/\/mastersul.com.br\/es\/servico\/logistica-internacional\/","og_site_name":"Mastersul","article_modified_time":"2022-10-13T13:20:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mastersul.com.br\/servico\/logistica-internacional\/","url":"https:\/\/mastersul.com.br\/servico\/logistica-internacional\/","name":"Log\u00edstica Internacional - Mastersul","isPartOf":{"@id":"https:\/\/mastersul.com.br\/#website"},"datePublished":"2022-07-18T03:05:31+00:00","dateModified":"2022-10-13T13:20:59+00:00","breadcrumb":{"@id":"https:\/\/mastersul.com.br\/servico\/logistica-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mastersul.com.br\/servico\/logistica-internacional\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mastersul.com.br\/servico\/logistica-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mastersul.com.br\/"},{"@type":"ListItem","position":2,"name":"Servi\u00e7os","item":"https:\/\/mastersul.com.br\/servico\/"},{"@type":"ListItem","position":3,"name":"Log\u00edstica Internacional"}]},{"@type":"WebSite","@id":"https:\/\/mastersul.com.br\/#website","url":"https:\/\/mastersul.com.br\/","name":"Mastersul","description":"Solu\u00e7\u00e3o log\u00edstica e aduaneira para a sua empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mastersul.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/servico\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/servico"}],"about":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/types\/servico"}],"wp:attachment":[{"href":"https:\/\/mastersul.com.br\/es\/wp-json\/wp\/v2\/media?parent=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}